{"id":23699,"date":"2021-09-14T17:28:40","date_gmt":"2021-09-14T10:28:40","guid":{"rendered":"http:\/\/prakannews.com\/home\/?p=23699"},"modified":"2021-09-14T17:28:42","modified_gmt":"2021-09-14T10:28:42","slug":"%e0%b8%97%e0%b9%88%e0%b8%b2%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%a2%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%b8%e0%b8%a7%e0%b8%a3%e0%b8%a3%e0%b8%93%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%88-7","status":"publish","type":"post","link":"https:\/\/prakannews.com\/home\/2021\/09\/14\/%e0%b8%97%e0%b9%88%e0%b8%b2%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%a2%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%b8%e0%b8%a7%e0%b8%a3%e0%b8%a3%e0%b8%93%e0%b8%a0%e0%b8%b9%e0%b8%a1%e0%b8%b4%e0%b8%88-7\/","title":{"rendered":"\u0e17\u0e48\u0e32\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e22\u0e32\u0e19\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e20\u0e39\u0e21\u0e34\u0e08\u0e31\u0e14\u0e1d\u0e36\u0e01\u0e0b\u0e49\u0e2d\u0e21\u0e41\u0e1c\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e27\u0e32\u0e21\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2564"},"content":{"rendered":"\n<h3 class=\"has-vivid-red-color has-text-color wp-block-heading\">\u0e17\u0e48\u0e32\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e22\u0e32\u0e19\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e20\u0e39\u0e21\u0e34\u0e08\u0e31\u0e14\u0e1d\u0e36\u0e01\u0e0b\u0e49\u0e2d\u0e21\u0e41\u0e1c\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e27\u0e32\u0e21\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 (Business Continuity Plan : \u0e41\u0e1c\u0e19 BCP) \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2564 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e23\u0e31\u0e01\u0e29\u0e32\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e22\u0e32\u0e19 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1c\u0e39\u0e49\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e43\u0e2b\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u0e01\u0e23\u0e13\u0e35\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e08\u0e32\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e08\u0e19\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e34\u0e14\u0e01\u0e32\u0e23\u0e2b\u0e22\u0e38\u0e14\u0e0a\u0e30\u0e07\u0e31\u0e01<\/h3>\n\n\n\n<p>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19 14 \u0e01.\u0e22.64 <strong>\u0e19\u0e32\u0e22\u0e01\u0e34\u0e15\u0e15\u0e34\u0e1e\u0e07\u0e28\u0e4c \u0e01\u0e34\u0e15\u0e15\u0e34\u0e02\u0e08\u0e23<\/strong> \u0e23\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e17\u0e48\u0e32\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e22\u0e32\u0e19\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e20\u0e39\u0e21\u0e34 (\u0e2a\u0e32\u0e22\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 1)<br>\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e17\u0e48\u0e32\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e22\u0e32\u0e19\u0e44\u0e17\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19) (\u0e17\u0e2d\u0e17.) \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e0b\u0e49\u0e2d\u0e21\u0e41\u0e1c\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e27\u0e32\u0e21\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 (Business Continuity Plan : BCP) \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2564 \u0e40\u0e1b\u0e34\u0e14\u0e40\u0e1c\u0e22\u0e27\u0e48\u0e32\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e43\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e2d\u0e22\u0e39\u0e48\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e23\u0e48\u0e23\u0e30\u0e1a\u0e32\u0e14\u0e02\u0e2d\u0e07\u0e42\u0e23\u0e04\u0e15\u0e34\u0e14\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e44\u0e27\u0e23\u0e31\u0e2a\u0e42\u0e04\u0e42\u0e23\u0e19\u0e32 2019(COVID-19) \u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e43\u0e2b\u0e49\u0e17\u0e48\u0e32\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e22\u0e32\u0e19\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e20\u0e39\u0e21\u0e34 (\u0e17\u0e2a\u0e20.) \u0e15\u0e49\u0e2d\u0e07\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e0b\u0e49\u0e2d\u0e21\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e1a\u0e19\u0e42\u0e15\u0e4a\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e08\u0e33\u0e25\u0e2d\u0e07 (Table-top Exercise) \u0e42\u0e14\u0e22\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e17\u0e32\u0e07\u0e44\u0e01\u0e25\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a Video Conference \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e13\u0e30\u0e17\u0e33\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 \u0e04\u0e27\u0e32\u0e21\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e41\u0e1c\u0e19 BCP \u0e41\u0e25\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e19\u0e33\u0e44\u0e1b\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e \u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e0b\u0e49\u0e2d\u0e21\u0e44\u0e14\u0e49\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e08\u0e33\u0e25\u0e2d\u0e07 \u0e01\u0e23\u0e13\u0e35 \u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e25\u0e34\u0e07\u0e41\u0e25\u0e30\u0e01\u0e39\u0e49\u0e20\u0e31\u0e22\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e22\u0e32\u0e19 \u0e17\u0e2a\u0e20. \u0e15\u0e34\u0e14\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e44\u0e27\u0e23\u0e31\u0e2a\u0e42\u0e04\u0e42\u0e23\u0e19\u0e32 2019(COVID-19) \u0e40\u0e1b\u0e47\u0e19\u0e08\u0e33\u0e19\u0e27\u0e19\u0e21\u0e32\u0e01 \u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e43\u0e2b\u0e49\u0e15\u0e49\u0e2d\u0e07\u0e25\u0e14\u0e02\u0e35\u0e14\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e19\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e22\u0e32\u0e19\u0e25\u0e07 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e14\u0e49\u0e32\u0e19\u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e25\u0e34\u0e07\u0e41\u0e25\u0e30\u0e01\u0e39\u0e49\u0e20\u0e31\u0e22 (Level of protection) \u0e17\u0e35\u0e48\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e1e\u0e2d\u0e44\u0e14\u0e49\u0e15\u0e32\u0e21\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e25\u0e34\u0e07\u0e41\u0e25\u0e30\u0e01\u0e39\u0e49\u0e20\u0e31\u0e22\u0e2a\u0e19\u0e32\u0e21\u0e1a\u0e34\u0e19 (Aerodrome category for rescue and fire fighting)<\/p>\n\n\n\n<p><strong>\u0e19\u0e32\u0e22\u0e01\u0e34\u0e15\u0e15\u0e34\u0e1e\u0e07\u0e28\u0e4c<\/strong>\u0e2f \u0e01\u0e25\u0e48\u0e32\u0e27\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e27\u0e48\u0e32\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e41\u0e1c\u0e19 BCP \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e01\u0e32\u0e23\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e15\u0e48\u0e2d\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e08\u0e32\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e23\u0e48\u0e23\u0e30\u0e1a\u0e32\u0e14\u0e02\u0e2d\u0e07\u0e42\u0e23\u0e04\u0e15\u0e34\u0e14\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e44\u0e27\u0e23\u0e31\u0e2a\u0e42\u0e04\u0e42\u0e23\u0e19\u0e32 2019(COVID-19) \u0e43\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19 \u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e0b\u0e49\u0e2d\u0e21\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e14\u0e35\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e27\u0e34\u0e17\u0e22\u0e38\u0e01\u0e32\u0e23\u0e1a\u0e34\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e01\u0e2d\u0e07\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e04\u0e19\u0e40\u0e02\u0e49\u0e32\u0e40\u0e21\u0e37\u0e2d\u0e07 2 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e15\u0e23\u0e27\u0e08\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e48\u0e32\u0e19\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e42\u0e23\u0e04\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e34\u0e19\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e01\u0e32\u0e23\u0e1a\u0e34\u0e19\u0e44\u0e17\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e1a\u0e32\u0e07\u0e01\u0e2d\u0e01\u0e44\u0e1f\u0e25\u0e17\u0e4c\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e40\u0e0b\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e34\u0e19\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e40\u0e2d\u0e40\u0e2d\u0e2a\u0e44\u0e2d\u0e08\u0e35 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e0b\u0e49\u0e2d\u0e21\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e0b\u0e49\u0e2d\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e25\u0e38\u0e25\u0e48\u0e27\u0e07\u0e44\u0e1b\u0e44\u0e14\u0e49\u0e14\u0e49\u0e27\u0e22\u0e14\u0e35<\/p>\n\n\n\n<p>\u0e17\u0e2a\u0e20. \u0e40\u0e25\u0e47\u0e07\u0e40\u0e2b\u0e47\u0e19\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e08\u0e36\u0e07\u0e08\u0e31\u0e14\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e0b\u0e49\u0e2d\u0e21\u0e41\u0e1c\u0e19 BCP \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e19\u0e49\u0e2d\u0e22\u0e1b\u0e35\u0e25\u0e30 1 \u0e04\u0e23\u0e31\u0e49\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e2d\u0e35\u0e01\u0e17\u0e31\u0e49\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e32\u0e01\u0e32\u0e23\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e43\u0e2b\u0e49\u0e2a\u0e48\u0e27\u0e19\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e15\u0e32\u0e21\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e01\u0e34\u0e14\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e41\u0e1c\u0e19 BCP \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1f\u0e37\u0e49\u0e19\u0e04\u0e37\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e01\u0e25\u0e31\u0e1a\u0e2a\u0e39\u0e48\u0e2a\u0e20\u0e32\u0e1e\u0e1b\u0e01\u0e15\u0e34\u0e17\u0e48\u0e32\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e22\u0e32\u0e19\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e20\u0e39\u0e21\u0e34\u0e08\u0e31\u0e14\u0e1d\u0e36\u0e01\u0e0b\u0e49\u0e2d\u0e21\u0e41\u0e1c\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e27\u0e32\u0e21\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2564<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><a href=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2021\/09\/S__4825141.jpg\" data-rel=\"lightbox-image-0\" data-imagelightbox=\"0\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"229\" src=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2021\/09\/S__4825141-300x229.jpg\" alt=\"\" data-id=\"23702\" data-full-url=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2021\/09\/S__4825141.jpg\" data-link=\"http:\/\/prakannews.com\/home\/?attachment_id=23702\" class=\"wp-image-23702\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2021\/09\/S__4825141-300x229.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2021\/09\/S__4825141-402x307.jpg 402w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2021\/09\/S__4825141.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2021\/09\/S__4825142.jpg\" data-rel=\"lightbox-image-1\" data-imagelightbox=\"1\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"325\" src=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2021\/09\/S__4825142.jpg\" alt=\"\" data-id=\"23703\" data-full-url=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2021\/09\/S__4825142.jpg\" data-link=\"http:\/\/prakannews.com\/home\/?attachment_id=23703\" class=\"wp-image-23703\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2021\/09\/S__4825142.jpg 600w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2021\/09\/S__4825142-300x163.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2021\/09\/S__4825142-402x218.jpg 402w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2021\/09\/S__4825143.jpg\" data-rel=\"lightbox-image-2\" data-imagelightbox=\"2\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"338\" src=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2021\/09\/S__4825143.jpg\" alt=\"\" data-id=\"23704\" data-full-url=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2021\/09\/S__4825143.jpg\" data-link=\"http:\/\/prakannews.com\/home\/?attachment_id=23704\" class=\"wp-image-23704\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2021\/09\/S__4825143.jpg 600w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2021\/09\/S__4825143-300x169.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2021\/09\/S__4825143-402x226.jpg 402w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure><\/li><\/ul><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"292\" src=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2021\/09\/007thaitong-2.jpg\" alt=\"\" class=\"wp-image-23700\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2021\/09\/007thaitong-2.jpg 1000w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2021\/09\/007thaitong-2-300x88.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2021\/09\/007thaitong-2-768x224.jpg 768w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2021\/09\/007thaitong-2-402x117.jpg 402w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2021\/09\/007thaitong-2-819x239.jpg 819w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2021\/09\/Copy-2.jpg\" alt=\"\" class=\"wp-image-23701\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2021\/09\/Copy-2.jpg 1024w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2021\/09\/Copy-2-300x150.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2021\/09\/Copy-2-768x384.jpg 768w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2021\/09\/Copy-2-402x201.jpg 402w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2021\/09\/Copy-2-819x410.jpg 819w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u0e17\u0e48\u0e32\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e22\u0e32\u0e19\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e20\u0e39\u0e21\u0e34\u0e08\u0e31\u0e14\u0e1d\u0e36\u0e01\u0e0b\u0e49\u0e2d\u0e21\u0e41\u0e1c\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e27\u0e32\u0e21\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 (Business Continuity Plan : \u0e41\u0e1c\u0e19 BCP) \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2564<\/p>\n","protected":false},"author":2,"featured_media":23702,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-23699","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-31"],"_links":{"self":[{"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/posts\/23699"}],"collection":[{"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/comments?post=23699"}],"version-history":[{"count":1,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/posts\/23699\/revisions"}],"predecessor-version":[{"id":23705,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/posts\/23699\/revisions\/23705"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/media\/23702"}],"wp:attachment":[{"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/media?parent=23699"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/categories?post=23699"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/tags?post=23699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}