{"id":27896,"date":"2022-01-13T16:48:11","date_gmt":"2022-01-13T09:48:11","guid":{"rendered":"http:\/\/prakannews.com\/home\/?p=27896"},"modified":"2022-01-13T16:48:13","modified_gmt":"2022-01-13T09:48:13","slug":"%e0%b9%80%e0%b8%88%e0%b9%89%e0%b8%b2%e0%b8%ab%e0%b8%99%e0%b9%89%e0%b8%b2%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b9%81","status":"publish","type":"post","link":"https:\/\/prakannews.com\/home\/2022\/01\/13\/%e0%b9%80%e0%b8%88%e0%b9%89%e0%b8%b2%e0%b8%ab%e0%b8%99%e0%b9%89%e0%b8%b2%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%81%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b9%81\/","title":{"rendered":"\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e01\u0e2d\u0e07\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e23\u0e40\u0e17\u0e32\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e20\u0e31\u0e22\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e19\u0e04\u0e23\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e48\u0e19\u0e19\u0e49\u0e33\u0e22\u0e32\u0e06\u0e48\u0e32\u0e40\u0e0a\u0e37\u0e49\u0e2d"},"content":{"rendered":"\n<p>\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e01\u0e2d\u0e07\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e23\u0e40\u0e17\u0e32\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e20\u0e31\u0e22\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e19\u0e04\u0e23\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e48\u0e19\u0e19\u0e49\u0e33\u0e22\u0e32\u0e06\u0e48\u0e32\u0e40\u0e0a\u0e37\u0e49\u0e2d \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e23\u0e48\u0e23\u0e30\u0e1a\u0e32\u0e14\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e44\u0e27\u0e23\u0e31\u0e2a\u0e42\u0e04\u0e27\u0e34\u0e14 19 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e2a\u0e30\u0e1e\u0e32\u0e19\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e0b\u0e2d\u0e22\u0e42\u0e1a\u0e23\u0e32\u0e13 \u0e15.\u0e1b\u0e32\u0e01\u0e19\u0e49\u0e33 \u0e2d.\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e04\u0e23\u0e1a\u0e17\u0e31\u0e49\u0e07 31 \u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 13 \u0e21\u0e01\u0e23\u0e32\u0e04\u0e21 2565<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><a href=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1673.jpg\" data-rel=\"lightbox-image-0\" data-imagelightbox=\"0\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1673.jpg\" alt=\"\" data-id=\"27900\" data-full-url=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1673.jpg\" data-link=\"http:\/\/prakannews.com\/home\/?attachment_id=27900\" class=\"wp-image-27900\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1673.jpg 600w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1673-300x200.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1673-402x268.jpg 402w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1722.jpg\" data-rel=\"lightbox-image-1\" data-imagelightbox=\"1\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1722.jpg\" alt=\"\" data-id=\"27901\" data-full-url=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1722.jpg\" data-link=\"http:\/\/prakannews.com\/home\/?attachment_id=27901\" class=\"wp-image-27901\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1722.jpg 600w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1722-300x200.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1722-402x268.jpg 402w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1728.jpg\" data-rel=\"lightbox-image-2\" data-imagelightbox=\"2\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1728.jpg\" alt=\"\" data-id=\"27902\" data-full-url=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1728.jpg\" data-link=\"http:\/\/prakannews.com\/home\/?attachment_id=27902\" class=\"wp-image-27902\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1728.jpg 600w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1728-300x200.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1728-402x268.jpg 402w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1815.jpg\" data-rel=\"lightbox-image-3\" data-imagelightbox=\"3\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1815.jpg\" alt=\"\" data-id=\"27903\" data-full-url=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1815.jpg\" data-link=\"http:\/\/prakannews.com\/home\/?attachment_id=27903\" class=\"wp-image-27903\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1815.jpg 600w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1815-300x200.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1815-402x268.jpg 402w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1823.jpg\" data-rel=\"lightbox-image-4\" data-imagelightbox=\"4\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1823.jpg\" alt=\"\" data-id=\"27904\" data-full-url=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1823.jpg\" data-link=\"http:\/\/prakannews.com\/home\/?attachment_id=27904\" class=\"wp-image-27904\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1823.jpg 600w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1823-300x200.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1823-402x268.jpg 402w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1892.jpg\" data-rel=\"lightbox-image-5\" data-imagelightbox=\"5\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1892.jpg\" alt=\"\" data-id=\"27905\" data-full-url=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1892.jpg\" data-link=\"http:\/\/prakannews.com\/home\/?attachment_id=27905\" class=\"wp-image-27905\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1892.jpg 600w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1892-300x200.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1892-402x268.jpg 402w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1932.jpg\" data-rel=\"lightbox-image-6\" data-imagelightbox=\"6\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1932.jpg\" alt=\"\" data-id=\"27906\" data-full-url=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1932.jpg\" data-link=\"http:\/\/prakannews.com\/home\/?attachment_id=27906\" class=\"wp-image-27906\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1932.jpg 600w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1932-300x200.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1932-402x268.jpg 402w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1962.jpg\" data-rel=\"lightbox-image-7\" data-imagelightbox=\"7\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1962.jpg\" alt=\"\" data-id=\"27907\" data-full-url=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1962.jpg\" data-link=\"http:\/\/prakannews.com\/home\/?attachment_id=27907\" class=\"wp-image-27907\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1962.jpg 600w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1962-300x200.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1962-402x268.jpg 402w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1968.jpg\" data-rel=\"lightbox-image-8\" data-imagelightbox=\"8\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1968.jpg\" alt=\"\" data-id=\"27908\" data-full-url=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1968.jpg\" data-link=\"http:\/\/prakannews.com\/home\/?attachment_id=27908\" class=\"wp-image-27908\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1968.jpg 600w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1968-300x200.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1968-402x268.jpg 402w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1975.jpg\" data-rel=\"lightbox-image-9\" data-imagelightbox=\"9\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1975.jpg\" alt=\"\" data-id=\"27909\" data-full-url=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1975.jpg\" data-link=\"http:\/\/prakannews.com\/home\/?attachment_id=27909\" class=\"wp-image-27909\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1975.jpg 600w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1975-300x200.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/2O4A1975-402x268.jpg 402w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure><\/li><\/ul><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"591\" src=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/012Sportcenter-2.jpg\" alt=\"\" class=\"wp-image-27897\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/012Sportcenter-2.jpg 1000w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/012Sportcenter-2-300x177.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/012Sportcenter-2-768x454.jpg 768w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/012Sportcenter-2-402x238.jpg 402w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/012Sportcenter-2-819x484.jpg 819w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"164\" src=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/006Imperial-4.jpg\" alt=\"\" class=\"wp-image-27899\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/006Imperial-4.jpg 1000w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/006Imperial-4-300x49.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/006Imperial-4-768x126.jpg 768w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/006Imperial-4-402x66.jpg 402w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/01\/006Imperial-4-819x134.jpg 819w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e01\u0e2d\u0e07\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e23\u0e40\u0e17\u0e32\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e20\u0e31\u0e22\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e19\u0e04\u0e23\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e48\u0e19\u0e19\u0e49\u0e33\u0e22\u0e32\u0e06\u0e48\u0e32\u0e40\u0e0a\u0e37\u0e49\u0e2d \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e23\u0e48\u0e23\u0e30\u0e1a\u0e32\u0e14\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e44\u0e27\u0e23\u0e31\u0e2a\u0e42\u0e04\u0e27\u0e34\u0e14 19 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e2a\u0e30\u0e1e\u0e32\u0e19\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e0b\u0e2d\u0e22\u0e42\u0e1a\u0e23\u0e32\u0e13 \u0e15.\u0e1b\u0e32\u0e01\u0e19\u0e49\u0e33 \u0e2d.\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e04\u0e23\u0e1a\u0e17\u0e31\u0e49\u0e07 31 \u0e0a\u0e38\u0e21\u0e0a\u0e19 <\/p>\n","protected":false},"author":2,"featured_media":27902,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-27896","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-31"],"_links":{"self":[{"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/posts\/27896"}],"collection":[{"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/comments?post=27896"}],"version-history":[{"count":1,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/posts\/27896\/revisions"}],"predecessor-version":[{"id":27910,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/posts\/27896\/revisions\/27910"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/media\/27902"}],"wp:attachment":[{"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/media?parent=27896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/categories?post=27896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/tags?post=27896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}