{"id":33263,"date":"2022-05-19T17:00:27","date_gmt":"2022-05-19T10:00:27","guid":{"rendered":"http:\/\/prakannews.com\/home\/?p=33263"},"modified":"2022-05-19T17:00:30","modified_gmt":"2022-05-19T10:00:30","slug":"%e0%b8%9e%e0%b9%88%e0%b8%ad%e0%b9%80%e0%b8%a1%e0%b8%b7%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%b2%e0%b8%81%e0%b8%99%e0%b9%89%e0%b8%b3-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%98%e0%b8%b2%e0%b8%99%e0%b9%80%e0%b8%9b","status":"publish","type":"post","link":"https:\/\/prakannews.com\/home\/2022\/05\/19\/%e0%b8%9e%e0%b9%88%e0%b8%ad%e0%b9%80%e0%b8%a1%e0%b8%b7%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%b2%e0%b8%81%e0%b8%99%e0%b9%89%e0%b8%b3-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%98%e0%b8%b2%e0%b8%99%e0%b9%80%e0%b8%9b\/","title":{"rendered":"\u0e1e\u0e48\u0e2d\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e1b\u0e32\u0e01\u0e19\u0e49\u0e33 \u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e40\u0e1b\u0e34\u0e14\u0e07\u0e32\u0e19\u0e21\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e14\u0e35\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e1b\u0e32\u0e01\u0e19\u0e49\u0e33"},"content":{"rendered":"\n<p>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e27\u0e25\u0e32 16.30\u0e19. \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 18 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2565 \u0e17\u0e35\u0e48\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c\u0e2e\u0e2d\u0e25\u0e25\u0e4c \u0e0a\u0e31\u0e49\u0e19 1 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2d\u0e34\u0e21\u0e1e\u0e35\u0e40\u0e23\u0e35\u0e22\u0e25\u0e40\u0e27\u0e34\u0e25\u0e14\u0e4c \u0e2a\u0e33\u0e42\u0e23\u0e07 \u0e2d.\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e2f \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u0e40\u0e01\u0e29\u0e15\u0e23\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e07\u0e32\u0e19 <strong>\u201c\u0e21\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e14\u0e35\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e1b\u0e32\u0e01\u0e19\u0e49\u0e33\u201d<\/strong> \u0e02\u0e36\u0e49\u0e19 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 18 \u2013 24 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2565 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e01\u0e25\u0e38\u0e48\u0e21\u0e41\u0e21\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e27\u0e34\u0e2a\u0e32\u0e2b\u0e01\u0e34\u0e08\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e02\u0e2d\u0e07\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e44\u0e14\u0e49\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08 \u0e43\u0e19\u0e02\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e35\u0e48\u0e14\u0e35\u0e15\u0e32\u0e21\u0e2b\u0e25\u0e31\u0e01\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e23\u0e39\u0e49\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e27\u0e34\u0e16\u0e35\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e41\u0e25\u0e49\u0e27 \u0e22\u0e31\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e41\u0e25\u0e30\u0e02\u0e22\u0e32\u0e22\u0e15\u0e25\u0e32\u0e14\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e41\u0e21\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23 \u0e44\u0e14\u0e49\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e35\u0e48\u0e40\u0e14\u0e48\u0e19\u0e46 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e2d\u0e07\u0e14\u0e35\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e1b\u0e32\u0e01\u0e19\u0e49\u0e33 \u0e43\u0e2b\u0e49\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e01\u0e27\u0e49\u0e32\u0e07\u0e02\u0e27\u0e32\u0e07\u0e21\u0e32\u0e01\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19\u0e27\u0e34\u0e2a\u0e32\u0e2b\u0e01\u0e34\u0e08\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e43\u0e2b\u0e49\u0e0a\u0e32\u0e27\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u0e2b\u0e31\u0e19\u0e21\u0e32\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e17\u0e35\u0e48\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e14\u0e49\u0e43\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23<\/p>\n\n\n\n<p>\u0e42\u0e14\u0e22\u0e21\u0e35 <strong>\u0e19\u0e32\u0e22\u0e27\u0e31\u0e19\u0e0a\u0e31\u0e22 \u0e04\u0e07\u0e40\u0e01\u0e29\u0e21<\/strong> \u0e1c\u0e39\u0e49\u0e27\u0e48\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e01\u0e25\u0e48\u0e32\u0e27\u0e40\u0e1b\u0e34\u0e14\u0e07\u0e32\u0e19 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e21\u0e2d\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e1a\u0e31\u0e15\u0e23 \u0e41\u0e01\u0e48\u0e1c\u0e39\u0e49\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e0a\u0e19\u0e30\u0e40\u0e25\u0e34\u0e28 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e42\u0e14\u0e22\u0e21\u0e35 <strong>\u0e19\u0e32\u0e22\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e40\u0e23\u0e37\u0e2d\u0e07\u0e1e\u0e31\u0e19\u0e18\u0e4c<\/strong> \u0e40\u0e01\u0e29\u0e15\u0e23\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30<strong>\u0e19\u0e32\u0e22\u0e42\u0e2d\u0e2c\u0e32\u0e23 \u0e01\u0e34\u0e08\u0e40\u0e25\u0e34\u0e28\u0e44\u0e1e\u0e42\u0e23\u0e08\u0e19\u0e4c <\/strong>\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e0d\u0e48 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2d\u0e34\u0e21\u0e1e\u0e35\u0e40\u0e23\u0e35\u0e22\u0e25\u0e40\u0e27\u0e34\u0e25\u0e14\u0e4c \u0e2a\u0e33\u0e42\u0e23\u0e07 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22 <strong>\u0e19\u0e32\u0e22\u0e0a\u0e31\u0e22\u0e1e\u0e08\u0e19\u0e4c \u0e08\u0e23\u0e39\u0e0d\u0e1e\u0e07\u0e28\u0e4c \u0e19\u0e32\u0e22\u0e40\u0e08\u0e19\u0e40\u0e08\u0e15\u0e19\u0e4c \u0e40\u0e08\u0e15\u0e19\u0e32\u0e27\u0e34\u0e19<\/strong> \u0e23\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e27\u0e48\u0e32\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e2b\u0e31\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e41\u0e21\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e49\u0e27\u0e21\u0e07\u0e32\u0e23\u0e01\u0e31\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e04\u0e36\u0e01\u0e04\u0e31\u0e01<\/p>\n\n\n\n<p>\u0e42\u0e14\u0e22\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e20\u0e32\u0e22\u0e43\u0e19\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e08\u0e31\u0e14\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e08\u0e31\u0e14\u0e41\u0e2a\u0e14\u0e07 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e08\u0e32\u0e01\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e0a\u0e32\u0e27\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\u0e42\u0e14\u0e22\u0e15\u0e23\u0e07 \u0e01\u0e27\u0e48\u0e32 80 \u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e08\u0e32\u0e01\u0e01\u0e25\u0e38\u0e48\u0e21\u0e41\u0e21\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e25\u0e38\u0e48\u0e21\u0e27\u0e34\u0e2a\u0e32\u0e2b\u0e01\u0e34\u0e08\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e1b\u0e25\u0e32\u0e2a\u0e25\u0e34\u0e14 \u0e01\u0e38\u0e49\u0e07\u0e40\u0e2b\u0e22\u0e35\u0e22\u0e14 \u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e19\u0e49\u0e33\u0e1b\u0e25\u0e32\u0e2b\u0e27\u0e32\u0e19 \u0e1c\u0e31\u0e01\u0e1b\u0e25\u0e2d\u0e14\u0e2a\u0e32\u0e23\u0e1e\u0e34\u0e29 \u0e01\u0e38\u0e49\u0e07 \u0e2b\u0e2d\u0e22 \u0e1b\u0e39 \u0e1b\u0e25\u0e32 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e2a\u0e14\u0e46 \u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e2b\u0e31\u0e15\u0e16\u0e01\u0e23\u0e23\u0e21\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e07\u0e32\u0e19\u0e22\u0e31\u0e07\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e01\u0e27\u0e48\u0e32 30 \u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e32\u0e18\u0e34\u0e15\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e41\u0e25\u0e30\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e1f\u0e23\u0e35! \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e39\u0e49\u0e2a\u0e19\u0e43\u0e08\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e32\u0e23\u0e2a\u0e32\u0e18\u0e34\u0e15 \u0e19\u0e33\u0e44\u0e1b\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e32\u0e0a\u0e35\u0e1e\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49 \u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3318.jpg\" data-rel=\"lightbox-image-0\" data-imagelightbox=\"0\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" data-id=\"33266\" src=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3318.jpg\" alt=\"\" class=\"wp-image-33266\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3318.jpg 600w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3318-300x200.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3318-402x268.jpg 402w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3319.jpg\" data-rel=\"lightbox-image-1\" data-imagelightbox=\"1\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" data-id=\"33270\" src=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3319.jpg\" alt=\"\" class=\"wp-image-33270\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3319.jpg 600w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3319-300x200.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3319-402x268.jpg 402w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3322.jpg\" data-rel=\"lightbox-image-2\" data-imagelightbox=\"2\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" data-id=\"33273\" src=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3322.jpg\" alt=\"\" class=\"wp-image-33273\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3322.jpg 600w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3322-300x200.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3322-402x268.jpg 402w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3325.jpg\" data-rel=\"lightbox-image-3\" data-imagelightbox=\"3\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" data-id=\"33268\" src=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3325.jpg\" alt=\"\" class=\"wp-image-33268\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3325.jpg 600w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3325-300x200.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3325-402x268.jpg 402w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3334.jpg\" data-rel=\"lightbox-image-4\" data-imagelightbox=\"4\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" data-id=\"33267\" src=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3334.jpg\" alt=\"\" class=\"wp-image-33267\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3334.jpg 600w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3334-300x200.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3334-402x268.jpg 402w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3338.jpg\" data-rel=\"lightbox-image-5\" data-imagelightbox=\"5\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" data-id=\"33278\" src=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3338.jpg\" alt=\"\" class=\"wp-image-33278\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3338.jpg 600w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3338-300x200.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3338-402x268.jpg 402w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3340.jpg\" data-rel=\"lightbox-image-6\" data-imagelightbox=\"6\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" data-id=\"33269\" src=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3340.jpg\" alt=\"\" class=\"wp-image-33269\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3340.jpg 600w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3340-300x200.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3340-402x268.jpg 402w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3346.jpg\" data-rel=\"lightbox-image-7\" data-imagelightbox=\"7\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" data-id=\"33277\" src=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3346.jpg\" alt=\"\" class=\"wp-image-33277\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3346.jpg 600w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3346-300x200.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3346-402x268.jpg 402w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3350.jpg\" data-rel=\"lightbox-image-8\" data-imagelightbox=\"8\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" data-id=\"33271\" src=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3350.jpg\" alt=\"\" class=\"wp-image-33271\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3350.jpg 600w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3350-300x200.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3350-402x268.jpg 402w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3359.jpg\" data-rel=\"lightbox-image-9\" data-imagelightbox=\"9\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" data-id=\"33272\" src=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3359.jpg\" alt=\"\" class=\"wp-image-33272\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3359.jpg 600w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3359-300x200.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3359-402x268.jpg 402w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3374.jpg\" data-rel=\"lightbox-image-10\" data-imagelightbox=\"10\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" data-id=\"33279\" src=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3374.jpg\" alt=\"\" class=\"wp-image-33279\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3374.jpg 600w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3374-300x200.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3374-402x268.jpg 402w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3377.jpg\" data-rel=\"lightbox-image-11\" data-imagelightbox=\"11\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" data-id=\"33275\" src=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3377.jpg\" alt=\"\" class=\"wp-image-33275\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3377.jpg 600w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3377-300x200.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3377-402x268.jpg 402w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3395.jpg\" data-rel=\"lightbox-image-12\" data-imagelightbox=\"12\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" data-id=\"33274\" src=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3395.jpg\" alt=\"\" class=\"wp-image-33274\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3395.jpg 600w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3395-300x200.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3395-402x268.jpg 402w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3399.jpg\" data-rel=\"lightbox-image-13\" data-imagelightbox=\"13\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" data-id=\"33276\" src=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3399.jpg\" alt=\"\" class=\"wp-image-33276\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3399.jpg 600w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3399-300x200.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3399-402x268.jpg 402w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3402.jpg\" data-rel=\"lightbox-image-14\" data-imagelightbox=\"14\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" data-id=\"33280\" src=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3402.jpg\" alt=\"\" class=\"wp-image-33280\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3402.jpg 600w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3402-300x200.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3402-402x268.jpg 402w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3406.jpg\" data-rel=\"lightbox-image-15\" data-imagelightbox=\"15\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" data-id=\"33282\" src=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3406.jpg\" alt=\"\" class=\"wp-image-33282\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3406.jpg 600w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3406-300x200.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3406-402x268.jpg 402w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3411.jpg\" data-rel=\"lightbox-image-16\" data-imagelightbox=\"16\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" data-id=\"33281\" src=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3411.jpg\" alt=\"\" class=\"wp-image-33281\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3411.jpg 600w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3411-300x200.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/IMG_3411-402x268.jpg 402w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"292\" src=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/007thaitong-Copy-6.jpg\" alt=\"\" class=\"wp-image-33264\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/007thaitong-Copy-6.jpg 1000w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/007thaitong-Copy-6-300x88.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/007thaitong-Copy-6-768x224.jpg 768w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/007thaitong-Copy-6-402x117.jpg 402w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/007thaitong-Copy-6-819x239.jpg 819w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"593\" src=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/015supmunkong-Copy-7.jpg\" alt=\"\" class=\"wp-image-33265\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/015supmunkong-Copy-7.jpg 1000w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/015supmunkong-Copy-7-300x178.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/015supmunkong-Copy-7-768x455.jpg 768w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/015supmunkong-Copy-7-402x238.jpg 402w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2022\/05\/015supmunkong-Copy-7-819x486.jpg 819w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e27\u0e25\u0e32 16.30\u0e19. \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 18 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2565 \u0e17\u0e35\u0e48\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c\u0e2e\u0e2d\u0e25\u0e25\u0e4c \u0e0a\u0e31\u0e49\u0e19 1 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2d\u0e34\u0e21\u0e1e\u0e35\u0e40\u0e23\u0e35\u0e22\u0e25\u0e40\u0e27\u0e34\u0e25\u0e14\u0e4c \u0e2a\u0e33\u0e42\u0e23\u0e07 \u0e2d.\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e2f \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u0e40\u0e01\u0e29\u0e15\u0e23\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23<\/p>\n","protected":false},"author":2,"featured_media":33279,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-33263","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-31"],"_links":{"self":[{"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/posts\/33263"}],"collection":[{"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/comments?post=33263"}],"version-history":[{"count":1,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/posts\/33263\/revisions"}],"predecessor-version":[{"id":33283,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/posts\/33263\/revisions\/33283"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/media\/33279"}],"wp:attachment":[{"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/media?parent=33263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/categories?post=33263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/tags?post=33263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}