{"id":52158,"date":"2023-04-09T10:29:05","date_gmt":"2023-04-09T03:29:05","guid":{"rendered":"https:\/\/prakannews.com\/home\/?p=52158"},"modified":"2023-04-09T10:29:08","modified_gmt":"2023-04-09T03:29:08","slug":"%e0%b9%80%e0%b8%97%e0%b8%a8%e0%b8%9a%e0%b8%b2%e0%b8%a5%e0%b8%95%e0%b8%b3%e0%b8%9a%e0%b8%a5%e0%b8%9a%e0%b8%b2%e0%b8%87%e0%b8%9b%e0%b8%b9-%e0%b8%a3%e0%b9%88%e0%b8%a7%e0%b8%a1%e0%b8%97%e0%b8%b3","status":"publish","type":"post","link":"https:\/\/prakannews.com\/home\/2023\/04\/09\/%e0%b9%80%e0%b8%97%e0%b8%a8%e0%b8%9a%e0%b8%b2%e0%b8%a5%e0%b8%95%e0%b8%b3%e0%b8%9a%e0%b8%a5%e0%b8%9a%e0%b8%b2%e0%b8%87%e0%b8%9b%e0%b8%b9-%e0%b8%a3%e0%b9%88%e0%b8%a7%e0%b8%a1%e0%b8%97%e0%b8%b3\/","title":{"rendered":"\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e1a\u0e32\u0e07\u0e1b\u0e39 \u201c\u0e23\u0e48\u0e27\u0e21\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e14\u0e35 \u0e1b\u0e25\u0e48\u0e2d\u0e22\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1b\u0e39 \u0e04\u0e37\u0e19\u0e2a\u0e39\u0e48\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u201d \u0e43\u0e19\u0e1b\u0e35\u0e19\u0e35\u0e49\u0e21\u0e35\u0e01\u0e32\u0e23\u0e44\u0e16\u0e48\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1b\u0e39\u0e17\u0e30\u0e40\u0e25 \u0e01\u0e27\u0e48\u0e32 4,000 \u0e01\u0e34\u0e42\u0e25\u0e01\u0e23\u0e31\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e38\u0e14\u0e21\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e19\u0e34\u0e40\u0e27\u0e28\u0e41\u0e25\u0e30\u0e02\u0e22\u0e32\u0e22\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e27\u0e25\u0e32 10.00 \u0e19. \u0e02\u0e2d\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 8 \u0e40\u0e21\u0e29\u0e32\u0e22\u0e19 2566 <strong>\u0e1e\u0e23\u0e30\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e42\u0e2a\u0e20\u0e32 \u0e2a\u0e21\u0e42\u0e13<\/strong> \u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e2a\u0e07\u0e06\u0e4c\u0e27\u0e31\u0e14\u0e41\u0e2a\u0e07\u0e18\u0e23\u0e23\u0e21\u0e27\u0e31\u0e07\u0e40\u0e02\u0e32\u0e40\u0e02\u0e35\u0e22\u0e27 \u0e15\u0e33\u0e1a\u0e25\u0e27\u0e31\u0e07\u0e19\u0e49\u0e33\u0e40\u0e02\u0e35\u0e22\u0e27 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e27\u0e31\u0e07\u0e19\u0e49\u0e33\u0e40\u0e02\u0e35\u0e22\u0e27 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u0e19\u0e33\u0e04\u0e13\u0e30\u0e28\u0e34\u0e29\u0e22\u0e32\u0e19\u0e38\u0e28\u0e34\u0e29\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e31\u0e25\u0e22\u0e32\u0e13\u0e21\u0e34\u0e15 \u0e1e\u0e23\u0e30\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e42\u0e2a\u0e20\u0e32 \u0e2a\u0e21\u0e42\u0e13 <strong>\u201c\u0e23\u0e48\u0e27\u0e21\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e14\u0e35 \u0e1b\u0e25\u0e48\u0e2d\u0e22\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1b\u0e39 \u0e04\u0e37\u0e19\u0e2a\u0e39\u0e48\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u201d<\/strong> \u0e13 \u0e2a\u0e16\u0e32\u0e19\u0e15\u0e32\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e1a\u0e32\u0e07\u0e1b\u0e39 \u0e15.\u0e1a\u0e32\u0e07\u0e1b\u0e39\u0e43\u0e2b\u0e21\u0e48 \u0e2d.\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e02\u0e22\u0e32\u0e22\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33\u0e17\u0e35\u0e48\u0e08\u0e31\u0e14\u0e02\u0e36\u0e49\u0e19\u0e43\u0e19\u0e17\u0e38\u0e01 \u0e46 \u0e1b\u0e35 \u0e42\u0e14\u0e22\u0e43\u0e19\u0e1b\u0e35\u0e19\u0e35\u0e49\u0e44\u0e14\u0e49\u0e21\u0e35\u0e01\u0e32\u0e23\u0e44\u0e16\u0e48\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1b\u0e39\u0e17\u0e30\u0e40\u0e25\u0e01\u0e27\u0e48\u0e32 4,000 \u0e01\u0e34\u0e42\u0e25\u0e01\u0e23\u0e31\u0e21 \u0e42\u0e14\u0e22\u0e21\u0e35<strong>\u0e19\u0e32\u0e22\u0e18\u0e35\u0e23\u0e1e\u0e25 \u0e0a\u0e38\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d<\/strong> \u0e19\u0e32\u0e22\u0e01\u0e40\u0e17\u0e28\u0e21\u0e19\u0e15\u0e23\u0e35\u0e15\u0e33\u0e1a\u0e25\u0e1a\u0e32\u0e07\u0e1b\u0e39 \u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e2b\u0e31\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e1a\u0e32\u0e07\u0e1b\u0e39 <strong>\u0e1e\u0e31\u0e19\u0e40\u0e2d\u0e01 \u0e14\u0e34\u0e15\u0e16\u0e4c \u0e2a\u0e39\u0e22\u0e30\u0e19\u0e31\u0e19\u0e17\u0e4c<\/strong> \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e01\u0e2d\u0e07\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e1c\u0e48\u0e2d\u0e19 \u0e01\u0e23\u0e21\u0e1e\u0e25\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23\u0e17\u0e2b\u0e32\u0e23\u0e1a\u0e01 <strong>\u0e1e\u0e25.\u0e15.\u0e15.\u0e1e\u0e31\u0e25\u0e25\u0e20 \u0e41\u0e2d\u0e23\u0e48\u0e21\u0e2b\u0e25\u0e49\u0e32<\/strong> \u0e1c\u0e39\u0e49\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e33\u0e23\u0e27\u0e08\u0e20\u0e39\u0e18\u0e23\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e17\u0e2b\u0e32\u0e23 \u0e15\u0e33\u0e23\u0e27\u0e08 \u0e41\u0e25\u0e30\u0e1e\u0e35\u0e48\u0e19\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19 \u0e08\u0e32\u0e01\u0e17\u0e31\u0e48\u0e27\u0e2a\u0e32\u0e23\u0e17\u0e34\u0e28 \u0e01\u0e27\u0e48\u0e32 500 \u0e04\u0e19 \u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e21\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e01\u0e31\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e04\u0e36\u0e01\u0e15\u0e31\u0e01       <\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"2\" width=\"1170\" height=\"658\" src=\"https:\/\/www.youtube.com\/embed\/oLcLQpprygs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e14\u0e49\u0e27\u0e22<strong>\u0e1e\u0e23\u0e30\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e42\u0e2a\u0e20\u0e32 \u0e2a\u0e21\u0e42\u0e13<\/strong> \u0e44\u0e14\u0e49\u0e40\u0e25\u0e47\u0e07\u0e40\u0e2b\u0e47\u0e19\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e17\u0e30\u0e40\u0e25 \u0e17\u0e35\u0e48\u0e19\u0e31\u0e1a\u0e27\u0e31\u0e19\u0e08\u0e30\u0e25\u0e14\u0e19\u0e49\u0e2d\u0e22\u0e25\u0e07 \u0e08\u0e36\u0e07\u0e44\u0e14\u0e49\u0e19\u0e33\u0e1e\u0e32\u0e04\u0e13\u0e30\u0e28\u0e34\u0e29\u0e22\u0e32\u0e19\u0e38\u0e28\u0e34\u0e29\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e23\u0e48\u0e27\u0e21\u0e17\u0e33\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1a\u0e33\u0e40\u0e1e\u0e47\u0e0d\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e15\u0e48\u0e2d\u0e1c\u0e37\u0e19\u0e41\u0e1c\u0e48\u0e19\u0e14\u0e34\u0e19\u0e44\u0e17\u0e22 \u0e1b\u0e25\u0e48\u0e2d\u0e22\u0e1b\u0e39\u0e17\u0e30\u0e40\u0e25\u0e04\u0e37\u0e19\u0e2a\u0e39\u0e48\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e19\u0e34\u0e40\u0e27\u0e28\u0e1b\u0e48\u0e32\u0e0a\u0e32\u0e22\u0e40\u0e25\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07 \u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e41\u0e25\u0e30\u0e1b\u0e25\u0e39\u0e01\u0e1d\u0e31\u0e07\u0e43\u0e2b\u0e49\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e44\u0e14\u0e49\u0e15\u0e23\u0e30\u0e2b\u0e19\u0e31\u0e01\u0e16\u0e36\u0e07\u0e04\u0e38\u0e13\u0e04\u0e48\u0e32\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e19\u0e38\u0e23\u0e31\u0e01\u0e29\u0e4c\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33\u0e41\u0e25\u0e30\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e38\u0e14\u0e21\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21 \u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e31\u0e48\u0e19\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e08\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e19\u0e38\u0e23\u0e31\u0e01\u0e29\u0e4c\u0e41\u0e25\u0e30\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e1b\u0e39\u0e17\u0e30\u0e40\u0e25\u0e43\u0e19\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e04\u0e38\u0e49\u0e21\u0e04\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e04\u0e37\u0e19\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e38\u0e14\u0e21\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e43\u0e19\u0e23\u0e30\u0e22\u0e30\u0e22\u0e32\u0e27\u0e44\u0e14\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e14\u0e35 \u0e42\u0e14\u0e22\u0e21\u0e35 <strong>\u0e19\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1e\u0e23 \u0e40\u0e09\u0e25\u0e34\u0e21\u0e0a\u0e31\u0e22\u0e27\u0e31\u0e12\u0e19\u0e32 \u0e19\u0e32\u0e07\u0e13\u0e31\u0e10\u0e19\u0e01 \u0e40\u0e25\u0e37\u0e48\u0e2d\u0e21\u0e19\u0e34\u0e23\u0e31\u0e19\u0e14\u0e23 \u0e19\u0e32\u0e07\u0e1b\u0e38\u0e0d\u0e0d\u0e34\u0e28\u0e32 \u0e1b\u0e23\u0e31\u0e0a\u0e0d\u0e32\u0e17\u0e34\u0e1e\u0e32\u0e01\u0e23<\/strong> (\u0e04\u0e23\u0e39\u0e14\u0e27\u0e07) <strong>\u0e19\u0e32\u0e22\u0e01\u0e23\u0e13\u0e4c\u0e0a\u0e1e\u0e31\u0e12\u0e19\u0e4c \u0e14\u0e33\u0e23\u0e07\u0e04\u0e4c\u0e44\u0e0a\u0e22<\/strong> (\u0e04\u0e23\u0e39\u0e44\u0e01\u0e48\u0e1b\u0e4a\u0e2d\u0e1a) <strong>\u0e28\u0e34\u0e29\u0e22\u0e32\u0e19\u0e38\u0e28\u0e34\u0e29\u0e22\u0e4c\u0e1e\u0e23\u0e30\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e42\u0e2a\u0e20\u0e32 \u0e2a\u0e21\u0e42\u0e13<\/strong> \u0e08\u0e32\u0e01\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e21\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1b\u0e25\u0e48\u0e2d\u0e22\u0e1b\u0e39\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e14\u0e49\u0e27\u0e22<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8062.jpg\" data-rel=\"lightbox-image-0\" data-imagelightbox=\"0\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"415\" data-id=\"52161\" src=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8062.jpg\" alt=\"\" class=\"wp-image-52161\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8062.jpg 600w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8062-300x208.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8062-402x278.jpg 402w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8062-204x140.jpg 204w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8064.jpg\" data-rel=\"lightbox-image-1\" data-imagelightbox=\"1\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" data-id=\"52172\" src=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8064.jpg\" alt=\"\" class=\"wp-image-52172\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8064.jpg 600w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8064-300x200.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8064-402x268.jpg 402w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8068.jpg\" data-rel=\"lightbox-image-2\" data-imagelightbox=\"2\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" data-id=\"52164\" src=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8068.jpg\" alt=\"\" class=\"wp-image-52164\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8068.jpg 600w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8068-300x200.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8068-402x268.jpg 402w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" data-id=\"52175\" src=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8075.jpg\" alt=\"\" class=\"wp-image-52175\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8075.jpg 600w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8075-300x200.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8075-402x268.jpg 402w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8077.jpg\" data-rel=\"lightbox-image-3\" data-imagelightbox=\"3\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"411\" data-id=\"52169\" src=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8077.jpg\" alt=\"\" class=\"wp-image-52169\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8077.jpg 600w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8077-300x206.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8077-402x275.jpg 402w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8077-204x140.jpg 204w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8090.jpg\" data-rel=\"lightbox-image-4\" data-imagelightbox=\"4\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" data-id=\"52168\" src=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8090.jpg\" alt=\"\" class=\"wp-image-52168\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8090.jpg 600w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8090-300x200.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8090-402x268.jpg 402w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8094.jpg\" data-rel=\"lightbox-image-5\" data-imagelightbox=\"5\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" data-id=\"52165\" src=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8094.jpg\" alt=\"\" class=\"wp-image-52165\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8094.jpg 600w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8094-300x200.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8094-402x268.jpg 402w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8096.jpg\" data-rel=\"lightbox-image-6\" data-imagelightbox=\"6\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" data-id=\"52162\" src=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8096.jpg\" alt=\"\" class=\"wp-image-52162\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8096.jpg 600w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8096-300x200.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8096-402x268.jpg 402w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" data-id=\"52176\" src=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8099.jpg\" alt=\"\" class=\"wp-image-52176\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8099.jpg 600w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8099-300x200.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8099-402x268.jpg 402w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"406\" data-id=\"52177\" src=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8100.jpg\" alt=\"\" class=\"wp-image-52177\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8100.jpg 600w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8100-300x203.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8100-402x272.jpg 402w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8104.jpg\" data-rel=\"lightbox-image-7\" data-imagelightbox=\"7\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" data-id=\"52163\" src=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8104.jpg\" alt=\"\" class=\"wp-image-52163\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8104.jpg 600w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8104-300x200.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8104-402x268.jpg 402w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8106.jpg\" data-rel=\"lightbox-image-8\" data-imagelightbox=\"8\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" data-id=\"52173\" src=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8106.jpg\" alt=\"\" class=\"wp-image-52173\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8106.jpg 600w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8106-300x200.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8106-402x268.jpg 402w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8114.jpg\" data-rel=\"lightbox-image-9\" data-imagelightbox=\"9\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" data-id=\"52174\" src=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8114.jpg\" alt=\"\" class=\"wp-image-52174\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8114.jpg 600w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8114-300x200.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8114-402x268.jpg 402w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8115.jpg\" data-rel=\"lightbox-image-10\" data-imagelightbox=\"10\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" data-id=\"52167\" src=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8115.jpg\" alt=\"\" class=\"wp-image-52167\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8115.jpg 600w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8115-300x200.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8115-402x268.jpg 402w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8119.jpg\" data-rel=\"lightbox-image-11\" data-imagelightbox=\"11\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" data-id=\"52170\" src=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8119.jpg\" alt=\"\" class=\"wp-image-52170\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8119.jpg 600w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8119-300x200.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8119-402x268.jpg 402w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8131.jpg\" data-rel=\"lightbox-image-12\" data-imagelightbox=\"12\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" data-id=\"52171\" src=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8131.jpg\" alt=\"\" class=\"wp-image-52171\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8131.jpg 600w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8131-300x200.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8131-402x268.jpg 402w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8135.jpg\" data-rel=\"lightbox-image-13\" data-imagelightbox=\"13\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" data-id=\"52166\" src=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8135.jpg\" alt=\"\" class=\"wp-image-52166\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8135.jpg 600w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8135-300x200.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/IMG_8135-402x268.jpg 402w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"434\" src=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/010Psc-1.jpg\" alt=\"\" class=\"wp-image-52159\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/010Psc-1.jpg 1000w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/010Psc-1-300x130.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/010Psc-1-768x333.jpg 768w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/010Psc-1-402x174.jpg 402w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/010Psc-1-819x355.jpg 819w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"418\" src=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/009sukjarornpon-1.jpg\" alt=\"\" class=\"wp-image-52160\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/009sukjarornpon-1.jpg 1000w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/009sukjarornpon-1-300x125.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/009sukjarornpon-1-768x321.jpg 768w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/009sukjarornpon-1-402x168.jpg 402w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/04\/009sukjarornpon-1-819x342.jpg 819w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e27\u0e25\u0e32 10.00 \u0e19. \u0e02\u0e2d\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 8 \u0e40\u0e21\u0e29\u0e32\u0e22\u0e19 2566 \u0e1e\u0e23\u0e30\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e42\u0e2a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":52171,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-52158","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-31"],"_links":{"self":[{"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/posts\/52158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/comments?post=52158"}],"version-history":[{"count":1,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/posts\/52158\/revisions"}],"predecessor-version":[{"id":52178,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/posts\/52158\/revisions\/52178"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/media\/52171"}],"wp:attachment":[{"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/media?parent=52158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/categories?post=52158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/tags?post=52158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}