{"id":84618,"date":"2025-02-04T19:35:20","date_gmt":"2025-02-04T12:35:20","guid":{"rendered":"https:\/\/prakannews.com\/home\/?p=84618"},"modified":"2025-02-04T19:35:23","modified_gmt":"2025-02-04T12:35:23","slug":"%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%a5%e0%b8%81%e0%b9%80%e0%b8%9b%e0%b8%a5%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%99%e0%b8%a7%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%98","status":"publish","type":"post","link":"https:\/\/prakannews.com\/home\/2025\/02\/04\/%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%a5%e0%b8%81%e0%b9%80%e0%b8%9b%e0%b8%a5%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%99%e0%b8%a7%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%98\/","title":{"rendered":"\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e44\u0e17\u0e22-\u0e08\u0e35\u0e19 \u0e17\u0e35\u0e48\u0e08\u0e31\u0e14\u0e02\u0e36\u0e49\u0e19\u0e22\u0e34\u0e48\u0e07\u0e43\u0e2b\u0e0d\u0e48 \u0e17\u0e35\u0e48\u0e2b\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e43\u0e2b\u0e0d\u0e48\u0e01\u0e23\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u201c\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2a\u0e32\u0e04\u0e23\u0e40\u0e04\u0e40\u0e1a\u0e34\u0e49\u0e25\u0e08\u0e33\u0e01\u0e31\u0e14\u201d \u0e44\u0e14\u0e49\u0e02\u0e36\u0e49\u0e19\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e40\u0e14\u0e47\u0e01\u0e41\u0e25\u0e30\u0e40\u0e22\u0e32\u0e0a\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c"},"content":{"rendered":"\n<p><strong>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e27\u0e25\u0e32 09.00 \u0e19.\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 4 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2568 \u0e17\u0e35\u0e48\u0e2b\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e43\u0e2b\u0e0d\u0e48 \u0e0a\u0e31\u0e49\u0e19 3 \u0e01\u0e23\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e14\u0e23.\u0e1a\u0e23\u0e23\u0e13\u0e27\u0e31\u0e12\u0e19\u0e4c \u0e27\u0e31\u0e0a\u0e23\u0e01\u0e38\u0e25\u0e20\u0e34\u0e23\u0e21\u0e22\u0e4c \u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e42\u0e2d\u0e1b\u0e2d\u0e01\u0e32\u0e23\u0e14\u0e19\u0e15\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e43\u0e19\u0e10\u0e32\u0e19\u0e30\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e28\u0e34\u0e25\u0e1b\u0e4c\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e19\u0e32\u0e19\u0e32\u0e0a\u0e32\u0e15\u0e34 \u0e2d.\u0e1e\u0e23\u0e30\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e40\u0e08\u0e14\u0e35\u0e22\u0e4c \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u0e44\u0e14\u0e49\u0e08\u0e31\u0e14\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e44\u0e17\u0e22-\u0e08\u0e35\u0e19 \u0e19\u0e32\u0e19\u0e32\u0e0a\u0e32\u0e15\u0e34 2025 \u0e42\u0e14\u0e22\u0e21\u0e35 \u0e19.\u0e2a.\u0e2d\u0e31\u0e0d\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e42\u0e0a\u0e15\u0e34\u0e08\u0e23\u0e34\u0e22\u0e32\u0e27\u0e31\u0e12\u0e19\u0e4c \u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e23\u0e1c\u0e39\u0e49\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"43448ec7 23f4 4892 b96c 2af2dfe3768d\" width=\"1170\" height=\"658\" src=\"https:\/\/www.youtube.com\/embed\/AFnRJxellbk?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>\u0e20\u0e32\u0e22\u0e43\u0e19\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e08\u0e32\u0e01 <strong>\u0e21.\u0e23.\u0e27.\u0e19\u0e34\u0e27\u0e31\u0e15\u0e34 \u0e01\u0e31\u0e25\u0e1b\u0e4c\u0e22\u0e32\u0e13\u0e27\u0e07\u0e28\u0e4c <\/strong>\u0e02\u0e36\u0e49\u0e19\u0e01\u0e25\u0e48\u0e32\u0e27\u0e43\u0e2b\u0e49\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e04\u0e13\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e08\u0e35\u0e19 \u0e42\u0e14\u0e22\u0e21\u0e35 <strong>\u0e2b\u0e21\u0e48\u0e2d\u0e21\u0e2b\u0e25\u0e27\u0e07\u0e2a\u0e38\u0e18\u0e35\u0e40\u0e17\u0e1e \u0e08\u0e23\u0e39\u0e0d\u0e42\u0e23\u0e08\u0e19\u0e4c<\/strong> \u0e01\u0e25\u0e48\u0e32\u0e27\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e21\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27<\/p>\n\n\n\n<p>\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e22\u0e31\u0e07\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e08\u0e32\u0e01 <strong>Mr.\u0e01\u0e31\u0e27 \u0e0a\u0e39 \u0e15\u0e07 <\/strong>\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e08\u0e35\u0e19 \u0e08\u0e32\u0e01\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e40\u0e2a\u0e34\u0e48\u0e19 \u0e2b\u0e22\u0e32\u0e07 \u0e02\u0e36\u0e49\u0e19\u0e01\u0e25\u0e48\u0e32\u0e27\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e21\u0e32\u0e23\u0e48\u0e27\u0e21\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49<\/p>\n\n\n\n<p>\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e23\u0e44\u0e14\u0e49\u0e40\u0e0a\u0e34\u0e0d\u0e04\u0e13\u0e30\u0e04\u0e23\u0e39\u0e1d\u0e36\u0e01\u0e2a\u0e2d\u0e19\u0e14\u0e49\u0e32\u0e19\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e08\u0e32\u0e01\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e31\u0e48\u0e27\u0e17\u0e38\u0e01\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e41\u0e02\u0e01\u0e23\u0e31\u0e1a\u0e40\u0e0a\u0e34\u0e0d \u0e27\u0e35.\u0e44\u0e2d.\u0e1e\u0e35.\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e02\u0e36\u0e49\u0e19\u0e23\u0e31\u0e1a\u0e16\u0e49\u0e27\u0e22\u0e41\u0e25\u0e30\u0e43\u0e1a\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e1a\u0e31\u0e15\u0e23 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e08\u0e32\u0e01 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e2a\u0e32\u0e04\u0e23\u0e40\u0e04\u0e40\u0e1a\u0e34\u0e49\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e41\u0e25\u0e30\u0e40\u0e1e\u0e08\u0e02\u0e48\u0e32\u0e27 Morning news online \u0e23\u0e48\u0e27\u0e21\u0e02\u0e36\u0e49\u0e19\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e2f \u0e43\u0e19\u0e10\u0e32\u0e19\u0e30\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e40\u0e14\u0e47\u0e01\u0e41\u0e25\u0e30\u0e40\u0e22\u0e32\u0e0a\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c<\/p>\n\n\n\n<p>\u0e42\u0e14\u0e22\u0e20\u0e32\u0e22\u0e43\u0e19\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e08\u0e32\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e34\u0e19\u0e0a\u0e37\u0e48\u0e2d\u0e14\u0e31\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07 <strong>\u201c\u0e42\u0e09\u0e21\u0e09\u0e32\u0e22 \u0e2d\u0e23\u0e38\u0e13\u0e09\u0e32\u0e19\u201d<\/strong> \u0e19\u0e31\u0e01\u0e23\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e01\u0e23\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e02\u0e36\u0e49\u0e19\u0e02\u0e31\u0e1a\u0e01\u0e25\u0e48\u0e2d\u0e21\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e40\u0e1e\u0e25\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e1e\u0e40\u0e23\u0e32\u0e30 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e0a\u0e21\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e28\u0e34\u0e25\u0e1b\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e40\u0e14\u0e47\u0e01\u0e41\u0e25\u0e30\u0e40\u0e22\u0e32\u0e27\u0e0a\u0e19\u0e08\u0e32\u0e01 2 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e48\u0e27\u0e21\u0e41\u0e2a\u0e14\u0e07\u0e1a\u0e19\u0e40\u0e27\u0e17\u0e35\u0e08\u0e33\u0e19\u0e27\u0e19 32 \u0e0a\u0e38\u0e14\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e1c\u0e39\u0e49\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07\u0e40\u0e14\u0e47\u0e01\u0e41\u0e25\u0e30\u0e40\u0e22\u0e32\u0e27\u0e0a\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e01\u0e31\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e08\u0e33\u0e19\u0e27\u0e19\u0e21\u0e32\u0e01<\/p>\n\n\n\n<p>\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e08\u0e31\u0e14\u0e02\u0e36\u0e49\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e08\u0e32\u0e01\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e28\u0e34\u0e25\u0e1b\u0e4c\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e19\u0e32\u0e19\u0e32\u0e0a\u0e32\u0e15\u0e34 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e42\u0e2d\u0e1b\u0e2d\u0e01\u0e32\u0e23\u0e14\u0e19\u0e15\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e2a\u0e20\u0e32\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e08\u0e35\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e20\u0e32\u0e04\u0e35\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2a\u0e2d\u0e19\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e08\u0e35\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e08\u0e31\u0e14\u0e02\u0e36\u0e49\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19\u0e21\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e32\u0e27\u0e19\u0e32\u0e19\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u0e42\u0e14\u0e22\u0e21\u0e38\u0e48\u0e07\u0e21\u0e31\u0e48\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e40\u0e14\u0e47\u0e01\u0e41\u0e25\u0e30\u0e40\u0e22\u0e32\u0e0a\u0e19\u0e44\u0e14\u0e49\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e2d\u0e2d\u0e01\u0e43\u0e19\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e28\u0e34\u0e25\u0e1b\u0e34\u0e19\u0e14\u0e32\u0e27\u0e14\u0e27\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e2a\u0e37\u0e1a\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e48\u0e2d\u0e44\u0e1b<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" data-id=\"84623\" src=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92794_0.jpg\" alt=\"\" class=\"wp-image-84623\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92794_0.jpg 800w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92794_0-300x300.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92794_0-150x150.jpg 150w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92794_0-768x768.jpg 768w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92794_0-402x402.jpg 402w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92794_0-92x92.jpg 92w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92794_0-200x200.jpg 200w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92794_0-97x97.jpg 97w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" data-id=\"84626\" src=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92795_0.jpg\" alt=\"\" class=\"wp-image-84626\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92795_0.jpg 800w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92795_0-300x300.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92795_0-150x150.jpg 150w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92795_0-768x768.jpg 768w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92795_0-402x402.jpg 402w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92795_0-92x92.jpg 92w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92795_0-200x200.jpg 200w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92795_0-97x97.jpg 97w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" data-id=\"84621\" src=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92796_0.jpg\" alt=\"\" class=\"wp-image-84621\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92796_0.jpg 800w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92796_0-300x300.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92796_0-150x150.jpg 150w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92796_0-768x768.jpg 768w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92796_0-402x402.jpg 402w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92796_0-92x92.jpg 92w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92796_0-200x200.jpg 200w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92796_0-97x97.jpg 97w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" data-id=\"84624\" src=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92797_0.jpg\" alt=\"\" class=\"wp-image-84624\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92797_0.jpg 800w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92797_0-300x300.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92797_0-150x150.jpg 150w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92797_0-768x768.jpg 768w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92797_0-402x402.jpg 402w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92797_0-92x92.jpg 92w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92797_0-200x200.jpg 200w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92797_0-97x97.jpg 97w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92798_0.jpg\" data-rel=\"lightbox-image-0\" data-imagelightbox=\"0\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"370\" data-id=\"84619\" src=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92798_0.jpg\" alt=\"\" class=\"wp-image-84619\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92798_0.jpg 800w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92798_0-300x139.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92798_0-768x355.jpg 768w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92798_0-402x186.jpg 402w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" data-id=\"84622\" src=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92799_0.jpg\" alt=\"\" class=\"wp-image-84622\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92799_0.jpg 800w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92799_0-300x300.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92799_0-150x150.jpg 150w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92799_0-768x768.jpg 768w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92799_0-402x402.jpg 402w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92799_0-92x92.jpg 92w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92799_0-200x200.jpg 200w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92799_0-97x97.jpg 97w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" data-id=\"84628\" src=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92800_0.jpg\" alt=\"\" class=\"wp-image-84628\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92800_0.jpg 800w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92800_0-300x300.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92800_0-150x150.jpg 150w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92800_0-768x768.jpg 768w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92800_0-402x402.jpg 402w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92800_0-92x92.jpg 92w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92800_0-200x200.jpg 200w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92800_0-97x97.jpg 97w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" data-id=\"84625\" src=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92801.jpg\" alt=\"\" class=\"wp-image-84625\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92801.jpg 800w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92801-300x300.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92801-150x150.jpg 150w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92801-768x768.jpg 768w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92801-402x402.jpg 402w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92801-92x92.jpg 92w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92801-200x200.jpg 200w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92801-97x97.jpg 97w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"346\" data-id=\"84620\" src=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92802_0.jpg\" alt=\"\" class=\"wp-image-84620\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92802_0.jpg 800w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92802_0-300x130.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92802_0-768x332.jpg 768w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/02\/92802_0-402x174.jpg 402w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e27\u0e25\u0e32 09.00 \u0e19.\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 4 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2568 \u0e17\u0e35\u0e48\u0e2b\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e43 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":84623,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-84618","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-31"],"_links":{"self":[{"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/posts\/84618"}],"collection":[{"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/comments?post=84618"}],"version-history":[{"count":1,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/posts\/84618\/revisions"}],"predecessor-version":[{"id":84629,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/posts\/84618\/revisions\/84629"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/media\/84623"}],"wp:attachment":[{"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/media?parent=84618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/categories?post=84618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/tags?post=84618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}