{"id":91947,"date":"2025-10-25T13:54:55","date_gmt":"2025-10-25T06:54:55","guid":{"rendered":"https:\/\/prakannews.com\/home\/?p=91947"},"modified":"2025-10-25T13:54:57","modified_gmt":"2025-10-25T06:54:57","slug":"%e0%b8%88%e0%b8%b1%e0%b8%87%e0%b8%ab%e0%b8%a7%e0%b8%b1%e0%b8%94%e0%b8%aa%e0%b8%a1%e0%b8%b8%e0%b8%97%e0%b8%a3%e0%b8%9b%e0%b8%a3%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94","status":"publish","type":"post","link":"https:\/\/prakannews.com\/home\/2025\/10\/25\/%e0%b8%88%e0%b8%b1%e0%b8%87%e0%b8%ab%e0%b8%a7%e0%b8%b1%e0%b8%94%e0%b8%aa%e0%b8%a1%e0%b8%b8%e0%b8%97%e0%b8%a3%e0%b8%9b%e0%b8%a3%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94\/","title":{"rendered":"\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e25\u0e32\u0e14 \u201c\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e23\u0e32\u0e04\u0e32\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14 \u0e25\u0e14\u0e04\u0e48\u0e32\u0e04\u0e23\u0e2d\u0e07\u0e0a\u0e35\u0e1e \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 4"},"content":{"rendered":"\n<p><strong>\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e25\u0e32\u0e14 \u201c\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e23\u0e32\u0e04\u0e32\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14 \u0e25\u0e14\u0e04\u0e48\u0e32\u0e04\u0e23\u0e2d\u0e07\u0e0a\u0e35\u0e1e \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 4\u201d \u0e17\u0e35\u0e48 \u0e15\u0e25\u0e32\u0e14\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e1a\u0e32\u0e07\u0e40\u0e2a\u0e32\u0e18\u0e07 24-26 \u0e1e.\u0e22.\u0e19\u0e35\u0e49<\/strong><\/p>\n\n\n\n<p>\u0e40\u0e21\u0e34\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 24 \u0e15\u0e38\u0e25\u0e32\u0e04\u0e21 2568 \u0e19\u0e32\u0e22\u0e2a\u0e21\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c \u0e41\u0e01\u0e49\u0e27\u0e40\u0e2a\u0e19\u0e32 \u0e1b\u0e25\u0e31\u0e14\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e0a\u0e21\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u201c\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e23\u0e32\u0e04\u0e32\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14 \u0e25\u0e14\u0e04\u0e48\u0e32\u0e04\u0e23\u0e2d\u0e07\u0e0a\u0e35\u0e1e \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 4\u201d \u0e13 \u0e15\u0e25\u0e32\u0e14\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e1a\u0e32\u0e07\u0e40\u0e2a\u0e32\u0e18\u0e07 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u0e01\u0e33\u0e2b\u0e19\u0e14\u0e08\u0e31\u0e14\u0e02\u0e36\u0e49\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 24 &#8211; 26 \u0e15\u0e38\u0e25\u0e32\u0e04\u0e21 2568 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1a\u0e23\u0e23\u0e40\u0e17\u0e32\u0e20\u0e32\u0e23\u0e30\u0e04\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e42\u0e14\u0e22\u0e21\u0e35 \u0e19\u0e32\u0e22\u0e28\u0e23\u0e32\u0e27\u0e38\u0e18 \u0e44\u0e0a\u0e22\u0e01\u0e2d\u0e07 \u0e19\u0e32\u0e22\u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e1a\u0e32\u0e07\u0e40\u0e2a\u0e32\u0e18\u0e07 \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19<\/p>\n\n\n\n<p>\u0e07\u0e32\u0e19\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e08\u0e31\u0e14\u0e02\u0e36\u0e49\u0e19\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u0e21\u0e38\u0e48\u0e07\u0e40\u0e19\u0e49\u0e19\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e35\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e04\u0e23\u0e2d\u0e07\u0e0a\u0e35\u0e1e \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e23\u0e32\u0e04\u0e32\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e43\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e04\u0e27\u0e32\u0e21\u0e04\u0e38\u0e49\u0e21\u0e04\u0e48\u0e32\u0e41\u0e25\u0e30\u0e25\u0e14\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e08\u0e32\u0e01\u0e20\u0e32\u0e27\u0e30\u0e04\u0e48\u0e32\u0e04\u0e23\u0e2d\u0e07\u0e0a\u0e35\u0e1e\u0e17\u0e35\u0e48\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19<\/p>\n\n\n\n<p>\u0e1b\u0e25\u0e31\u0e14\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d \u0e08\u0e32\u0e01\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e1a\u0e32\u0e07\u0e40\u0e2a\u0e32\u0e18\u0e07 \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e25\u0e1a\u0e32\u0e07\u0e40\u0e2a\u0e32\u0e18\u0e07 \u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e15\u0e2d\u0e1a\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e14\u0e35\u0e43\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e0a\u0e38\u0e21\u0e0a\u0e21 \u0e21\u0e35\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19 \u0e42\u0e14\u0e22\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e22\u0e31\u0e07\u0e21\u0e35\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2d\u0e36\u0e01 2 \u0e04\u0e23\u0e31\u0e49\u0e07 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e08\u0e30\u0e08\u0e31\u0e14\u0e02\u0e36\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e15\u0e25\u0e32\u0e14\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e38\u0e02 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e1a\u0e32\u0e07\u0e1a\u0e48\u0e2d \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 7-9 \u0e1e\u0e24\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19 2568 \u0e19\u0e35\u0e49<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"681\" data-id=\"91948\" src=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/10\/167842_0-1024x681.jpg\" alt=\"\" class=\"wp-image-91948\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/10\/167842_0-1024x681.jpg 1024w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/10\/167842_0-300x200.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/10\/167842_0-768x511.jpg 768w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/10\/167842_0-402x267.jpg 402w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/10\/167842_0-819x545.jpg 819w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/10\/167842_0.jpg 1180w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"91950\" src=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/10\/167843_0-768x1024.jpg\" alt=\"\" class=\"wp-image-91950\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/10\/167843_0-768x1024.jpg 768w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/10\/167843_0-225x300.jpg 225w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/10\/167843_0-402x536.jpg 402w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/10\/167843_0-300x400.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/10\/167843_0-819x1092.jpg 819w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/10\/167843_0.jpg 1108w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"91949\" src=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/10\/167844_0-1024x768.jpg\" alt=\"\" class=\"wp-image-91949\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/10\/167844_0-1024x768.jpg 1024w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/10\/167844_0-300x225.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/10\/167844_0-768x576.jpg 768w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/10\/167844_0-402x302.jpg 402w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/10\/167844_0-819x614.jpg 819w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2025\/10\/167844_0.jpg 1477w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e25\u0e32\u0e14 \u201c\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e23\u0e32\u0e04\u0e32\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":91948,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-91947","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-3"],"_links":{"self":[{"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/posts\/91947"}],"collection":[{"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/comments?post=91947"}],"version-history":[{"count":1,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/posts\/91947\/revisions"}],"predecessor-version":[{"id":91951,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/posts\/91947\/revisions\/91951"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/media\/91948"}],"wp:attachment":[{"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/media?parent=91947"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/categories?post=91947"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/tags?post=91947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}