{"id":98683,"date":"2026-05-13T12:28:32","date_gmt":"2026-05-13T05:28:32","guid":{"rendered":"https:\/\/prakannews.com\/home\/?p=98683"},"modified":"2026-05-13T12:28:34","modified_gmt":"2026-05-13T05:28:34","slug":"%e0%b8%99%e0%b9%89%e0%b8%b3%e0%b8%94%e0%b8%b7%e0%b9%88%e0%b8%a1%e0%b9%80%e0%b8%ad%e0%b9%80%e0%b8%8b%e0%b8%b5%e0%b8%a2-%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%a9%e0%b8%b1%e0%b8%97%e0%b9%80%e0%b8%ad%e0%b9%80","status":"publish","type":"post","link":"https:\/\/prakannews.com\/home\/2026\/05\/13\/%e0%b8%99%e0%b9%89%e0%b8%b3%e0%b8%94%e0%b8%b7%e0%b9%88%e0%b8%a1%e0%b9%80%e0%b8%ad%e0%b9%80%e0%b8%8b%e0%b8%b5%e0%b8%a2-%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%a9%e0%b8%b1%e0%b8%97%e0%b9%80%e0%b8%ad%e0%b9%80\/","title":{"rendered":"\u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21\u0e40\u0e2d\u0e40\u0e0b\u0e35\u0e22 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e40\u0e2d\u0e40\u0e0b\u0e35\u0e22\u0e27\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e40\u0e1d\u0e48\u0e32\u0e27\u0e34\u0e01\u0e24\u0e15\u0e22\u0e38\u0e04\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e41\u0e1e\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18 \u0e25\u0e14-\u0e1b\u0e23\u0e30\u0e04\u0e2d\u0e07\u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e2a\u0e39\u0e49 \u0e2b\u0e25\u0e31\u0e07\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e01\u0e25\u0e32\u0e07\u0e14\u0e36\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e44\u0e17\u0e22\u0e27\u0e39\u0e1a"},"content":{"rendered":"\n<pre class=\"wp-block-code\"><code>\u0e08\u0e32\u0e01\u0e2a\u0e20\u0e32\u0e27\u0e30\u0e27\u0e34\u0e01\u0e24\u0e15\u0e23\u0e32\u0e04\u0e32\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e41\u0e1e\u0e07\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e25\u0e47\u0e01\u0e43\u0e2b\u0e0d\u0e48\u0e2b\u0e25\u0e32\u0e22\u0e41\u0e2b\u0e48\u0e07\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21\u0e17\u0e35\u0e48\u0e17\u0e38\u0e01\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e27\u0e48\u0e32\u0e08\u0e30\u0e21\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21\u0e01\u0e34\u0e19 \u0e25\u0e49\u0e27\u0e19\u0e41\u0e25\u0e49\u0e27\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e21\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e27\u0e14 \u0e1d\u0e32 \u0e09\u0e25\u0e32\u0e01\u0e02\u0e49\u0e32\u0e07\u0e02\u0e27\u0e14 \u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e21\u0e49\u0e41\u0e15\u0e48\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 \n\n\u0e14\u0e23.\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e40\u0e08\u0e15\u0e19\u0e4c\u0e17\u0e23\u0e07\u0e18\u0e23\u0e23\u0e21  \u0e19\u0e32\u0e22\u0e01\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u0e43\u0e19\u0e10\u0e32\u0e19\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e40\u0e2d\u0e40\u0e0b\u0e35\u0e22 \u0e27\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14  \u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 992 \u0e2b\u0e21\u0e39\u0e48 3 \u0e0b.\u0e2b\u0e21\u0e2d\u0e40\u0e2a\u0e19\u0e2d  \u0e16.\u0e40\u0e17\u0e1e\u0e32\u0e23\u0e31\u0e01\u0e29\u0e4c  \u0e15.\u0e40\u0e17\u0e1e\u0e32\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e2d.\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32  \u0e08\u0e32\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e2a\u0e39\u0e49\u0e23\u0e1a\u0e43\u0e19\u0e41\u0e16\u0e1a\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e01\u0e25\u0e32\u0e07\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e2d\u0e34\u0e2b\u0e23\u0e48\u0e32\u0e19\u0e01\u0e31\u0e1a\u0e2d\u0e34\u0e2a\u0e23\u0e32\u0e40\u0e2d\u0e25\u0e41\u0e25\u0e30\u0e2a\u0e2b\u0e23\u0e31\u0e10\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e32 \u0e44\u0e14\u0e49\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e15\u0e48\u0e2d\u0e23\u0e30\u0e1a\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e40\u0e23\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e32\u0e01  \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2d\u0e34\u0e2b\u0e23\u0e48\u0e32\u0e19\u0e08\u0e31\u0e14\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e23\u0e32\u0e22\u0e43\u0e2b\u0e0d\u0e48\u0e02\u0e2d\u0e07\u0e42\u0e25\u0e01\u0e41\u0e2b\u0e48\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e44\u0e14\u0e49\u0e0b\u0e37\u0e49\u0e2d\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e14\u0e34\u0e1a\u0e21\u0e32\u0e01\u0e25\u0e31\u0e48\u0e19\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e2b\u0e32\u0e01\u0e21\u0e2d\u0e07\u0e16\u0e36\u0e07\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e15\u0e48\u0e2d\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e23\u0e32  \u0e01\u0e47\u0e04\u0e07\u0e2b\u0e19\u0e35\u0e44\u0e21\u0e48\u0e1e\u0e49\u0e19\u0e40\u0e21\u0e47\u0e14\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e17\u0e35\u0e48\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e04\u0e32\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19\u0e08\u0e32\u0e01\u0e20\u0e32\u0e27\u0e30\u0e20\u0e31\u0e22\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e01\u0e25\u0e32\u0e07 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e40\u0e21\u0e47\u0e14\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e19\u0e31\u0e1a\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e08\u0e32\u0e01\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e01\u0e25\u0e31\u0e48\u0e19\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19<\/code><\/pre>\n\n\n\n<p>\u0e43\u0e19\u0e17\u0e38\u0e01\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e21\u0e47\u0e14\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e42\u0e14\u0e22\u0e15\u0e19\u0e21\u0e2d\u0e07\u0e27\u0e48\u0e32\u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 1 \u0e02\u0e27\u0e14 \u0e25\u0e49\u0e27\u0e19\u0e43\u0e0a\u0e49\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 100 \u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e47\u0e19\u0e15\u0e4c \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e27\u0e14\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e09\u0e25\u0e32\u0e01\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e1d\u0e32\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e1f\u0e34\u0e25\u0e21\u0e4c\u0e2b\u0e38\u0e49\u0e21\u0e41\u0e1e\u0e47\u0e04\u0e19\u0e49\u0e33\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e08\u0e32\u0e01\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e25\u0e49\u0e27\u0e19\u0e41\u0e25\u0e49\u0e27\u0e43\u0e19\u0e17\u0e38\u0e01\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e02\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e41\u0e25\u0e30\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e23\u0e32\u0e04\u0e32\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e41\u0e17\u0e1a\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e49\u0e19 \u0e19\u0e31\u0e1a\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e40\u0e01\u0e34\u0e14\u0e40\u0e2b\u0e15\u0e38\u0e01\u0e32\u0e23\u0e4c\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21\u0e43\u0e19\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e01\u0e25\u0e32\u0e07\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e1b\u0e25\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e32\u0e16\u0e36\u0e07\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2569 \u0e23\u0e32\u0e04\u0e32\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e15\u0e31\u0e27\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32 25 \u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e47\u0e19\u0e15\u0e4c \u0e19\u0e31\u0e49\u0e19\u0e01\u0e47\u0e2b\u0e21\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e27\u0e48\u0e32\u0e23\u0e32\u0e04\u0e32\u0e02\u0e27\u0e14 \u0e23\u0e32\u0e04\u0e32\u0e09\u0e25\u0e32\u0e01 \u0e23\u0e32\u0e04\u0e32\u0e1d\u0e32 \u0e41\u0e25\u0e30\u0e23\u0e32\u0e04\u0e32\u0e1f\u0e34\u0e25\u0e21\u0e4c\u0e17\u0e35\u0e48\u0e41\u0e1e\u0e47\u0e04\u0e02\u0e27\u0e14\u0e19\u0e49\u0e33 \u0e41\u0e25\u0e30\u0e23\u0e32\u0e04\u0e32\u0e04\u0e48\u0e32\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e1e\u0e1a\u0e27\u0e48\u0e32\u0e43\u0e19\u0e17\u0e38\u0e01\u0e2a\u0e31\u0e1b\u0e14\u0e32\u0e2b\u0e4c\u0e23\u0e32\u0e04\u0e32\u0e40\u0e21\u0e47\u0e14\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e01\u0e47\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e39\u0e48\u0e15\u0e25\u0e2d\u0e14 \u0e08\u0e19\u0e01\u0e23\u0e30\u0e17\u0e31\u0e48\u0e07\u0e1b\u0e25\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e21\u0e35\u0e19\u0e32\u0e04\u0e21\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 \u0e40\u0e21\u0e47\u0e14\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e01\u0e47\u0e40\u0e23\u0e34\u0e48\u0e21\u0e02\u0e32\u0e14\u0e15\u0e25\u0e32\u0e14 \u0e04\u0e37\u0e2d\u0e21\u0e35\u0e40\u0e07\u0e34\u0e19\u0e01\u0e47\u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e27\u0e14\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e21\u0e32 \u0e08\u0e36\u0e07\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2b\u0e19\u0e31\u0e01\u0e15\u0e48\u0e2d\u0e27\u0e07\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21\u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e1b\u0e48\u0e32\u0e02\u0e27\u0e14\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e0b\u0e36\u0e48\u0e07 \u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21\u0e40\u0e2d\u0e40\u0e0b\u0e35\u0e22\u0e40\u0e2d\u0e07 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e44\u0e14\u0e49\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e21\u0e32\u0e19\u0e32\u0e19 26 \u0e1b\u0e35\u0e41\u0e25\u0e49\u0e27 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e40\u0e23\u0e32\u0e21\u0e35\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e42\u0e23\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e27\u0e14\u0e17\u0e35\u0e48\u0e2a\u0e48\u0e07\u0e02\u0e27\u0e14\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e08\u0e33\u0e19\u0e27\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e42\u0e23\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e23\u0e32\u0e01\u0e47\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e48\u0e07\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e27\u0e14\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21\u0e25\u0e48\u0e27\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e46 \u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e0a\u0e48\u0e27\u0e22\u0e41\u0e1a\u0e48\u0e07\u0e40\u0e1a\u0e32\u0e20\u0e32\u0e23\u0e30\u0e01\u0e32\u0e23\u0e02\u0e32\u0e14\u0e41\u0e04\u0e25\u0e19\u0e02\u0e27\u0e14\u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2f \u0e40\u0e2b\u0e15\u0e38\u0e40\u0e1e\u0e23\u0e30\u0e27\u0e48\u0e32\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21\u0e40\u0e2d\u0e40\u0e0b\u0e35\u0e22 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e40\u0e2d\u0e40\u0e0b\u0e35\u0e22\u0e27\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e21\u0e32\u0e23\u0e4c\u0e04\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e41\u0e21\u0e49\u0e08\u0e30\u0e44\u0e21\u0e48\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21\u0e21\u0e32\u0e01\u0e19\u0e31\u0e01 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2f\u0e44\u0e14\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46\u0e2a\u0e48\u0e07\u0e2b\u0e25\u0e32\u0e22\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e0a\u0e48\u0e19 \u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u0e23\u0e31\u0e10\u0e27\u0e34\u0e2a\u0e32\u0e2b\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e44\u0e14\u0e49\u0e2a\u0e33\u0e23\u0e2d\u0e07\u0e02\u0e27\u0e14\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e21\u0e32\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e41\u0e23\u0e01\u201d<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>\u0e14\u0e23.\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e40\u0e08\u0e15\u0e19\u0e4c\u0e17\u0e23\u0e07\u0e18\u0e23\u0e23\u0e21 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e15\u0e48\u0e2d\u0e27\u0e48\u0e32 \u0e41\u0e21\u0e49\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e49\u0e23\u0e1a\u0e43\u0e19\u0e41\u0e16\u0e1a\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e01\u0e25\u0e32\u0e07 \u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e08\u0e1a\u0e2a\u0e34\u0e49\u0e19 \u0e19\u0e2d\u0e01\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e02\u0e32\u0e14\u0e41\u0e04\u0e25\u0e19\u0e40\u0e21\u0e47\u0e14\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e41\u0e25\u0e49\u0e27 \u0e22\u0e31\u0e07\u0e21\u0e35\u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35\u0e1a\u0e32\u0e07\u0e15\u0e31\u0e27\u0e17\u0e35\u0e48\u0e19\u0e33\u0e21\u0e32\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e27\u0e14\u0e17\u0e35\u0e48\u0e44\u0e17\u0e22\u0e2a\u0e31\u0e48\u0e07\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e32\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e43\u0e19\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e01\u0e25\u0e32\u0e07 \u0e22\u0e31\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e15\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e40\u0e0a\u0e48\u0e19\u0e01\u0e31\u0e19 \u0e42\u0e14\u0e22\u0e14\u0e39\u0e08\u0e32\u0e01\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e19\u0e49\u0e33\u0e14\u0e37\u0e49\u0e21\u0e2b\u0e25\u0e32\u0e22\u0e41\u0e2b\u0e48\u0e07 \u0e40\u0e23\u0e34\u0e48\u0e21\u0e21\u0e35\u0e01\u0e32\u0e23\u0e2b\u0e22\u0e38\u0e14\u0e0a\u0e30\u0e25\u0e2d\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e01\u0e31\u0e19\u0e1a\u0e49\u0e32\u0e07\u0e41\u0e25\u0e49\u0e27\u0e1a\u0e32\u0e07\u0e2a\u0e48\u0e27\u0e19 \u0e42\u0e14\u0e22\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e08\u0e30\u0e22\u0e37\u0e14\u0e22\u0e37\u0e49\u0e2d\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e22\u0e32\u0e27\u0e19\u0e32\u0e19\u0e41\u0e04\u0e48\u0e44\u0e2b\u0e19\u0e01\u0e47\u0e44\u0e21\u0e48\u0e21\u0e35\u0e43\u0e04\u0e23\u0e02\u0e32\u0e14\u0e40\u0e14\u0e32\u0e44\u0e14\u0e49  \u0e41\u0e15\u0e48\u0e17\u0e35\u0e48\u0e41\u0e19\u0e48\u0e46\u0e19\u0e31\u0e1a\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e1b\u0e25\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e21\u0e32\u0e08\u0e19\u0e16\u0e36\u0e07\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19  \u0e1e\u0e1a\u0e27\u0e48\u0e32\u0e23\u0e32\u0e04\u0e32\u0e40\u0e21\u0e47\u0e14\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e44\u0e14\u0e49\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e15\u0e31\u0e27\u0e23\u0e32\u0e04\u0e32\u0e02\u0e36\u0e49\u0e19\u0e41\u0e25\u0e49\u0e27 100 \u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e47\u0e19\u0e15\u0e4c  \u0e0b\u0e36\u0e48\u0e07\u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21\u0e40\u0e2d\u0e40\u0e0b\u0e35\u0e22\u0e17\u0e35\u0e48\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e40\u0e23\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e48\u0e07\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 \u0e40\u0e23\u0e32\u0e01\u0e47\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e04\u0e32\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e02\u0e36\u0e49\u0e19\u0e40\u0e25\u0e47\u0e01\u0e19\u0e49\u0e2d\u0e22  \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e23\u0e32\u0e40\u0e2d\u0e07\u0e01\u0e47\u0e40\u0e2b\u0e47\u0e19\u0e43\u0e08\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e25\u0e32\u0e22\u0e41\u0e15\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e08\u0e23\u0e34\u0e07\u0e46  \u0e41\u0e21\u0e49\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e40\u0e2d\u0e40\u0e0b\u0e35\u0e22\u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21\u0e08\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e25\u0e14\u0e15\u0e49\u0e19\u0e17\u0e38\u0e19\u0e25\u0e07\u0e41\u0e25\u0e49\u0e27\u0e17\u0e38\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e01\u0e47\u0e15\u0e32\u0e21  \u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2f\u0e40\u0e2d\u0e07\u0e01\u0e47\u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e25\u0e14\u0e15\u0e49\u0e19\u0e17\u0e38\u0e19\u0e25\u0e07\u0e44\u0e14\u0e49\u0e2d\u0e35\u0e01 \u0e42\u0e14\u0e22\u0e1a\u0e32\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e47\u0e43\u0e2b\u0e49\u0e04\u0e39\u0e48\u0e04\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e23\u0e31\u0e1a\u0e17\u0e23\u0e32\u0e1a\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e08\u0e32\u0e01\u0e15\u0e49\u0e19\u0e17\u0e38\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19\u0e41\u0e25\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e01\u0e31\u0e19\u0e41\u0e1a\u0e48\u0e07\u0e40\u0e1a\u0e32\u0e20\u0e32\u0e23\u0e30\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19  \u0e0b\u0e36\u0e48\u0e07\u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21\u0e40\u0e2d\u0e40\u0e0b\u0e35\u0e22\u0e40\u0e23\u0e32\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e22\u0e38\u0e07\u0e41\u0e25\u0e30\u0e08\u0e30\u0e1f\u0e31\u0e19\u0e1d\u0e48\u0e32\u0e27\u0e34\u0e01\u0e24\u0e15\u0e08\u0e32\u0e01\u0e20\u0e32\u0e27\u0e30\u0e40\u0e21\u0e47\u0e14\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e14\u0e17\u0e35\u0e48\u0e01\u0e33\u0e25\u0e31\u0e07\u0e02\u0e32\u0e14\u0e41\u0e04\u0e25\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e17\u0e38\u0e01\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e41\u0e25\u0e30\u0e17\u0e38\u0e01\u0e04\u0e19\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21  \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e1e\u0e39\u0e14\u0e04\u0e38\u0e22\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49 \u0e01\u0e47\u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e1e\u0e39\u0e14\u0e04\u0e38\u0e22\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e44\u0e21\u0e48\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e01\u0e32\u0e23\u0e15\u0e37\u0e48\u0e19\u0e15\u0e23\u0e30\u0e2b\u0e19\u0e01\u0e08\u0e32\u0e01\u0e40\u0e2b\u0e15\u0e38\u0e01\u0e32\u0e23\u0e4c\u0e20\u0e32\u0e27\u0e30\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21\u0e08\u0e19\u0e23\u0e32\u0e04\u0e32\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e41\u0e1e\u0e07<\/code><\/pre>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1477\" height=\"1108\" data-id=\"98685\" src=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/968707_0.jpg\" alt=\"\" class=\"wp-image-98685\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/968707_0.jpg 1477w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/968707_0-300x225.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/968707_0-1024x768.jpg 1024w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/968707_0-768x576.jpg 768w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/968707_0-402x302.jpg 402w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/968707_0-819x614.jpg 819w\" sizes=\"(max-width: 1477px) 100vw, 1477px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1476\" height=\"1109\" data-id=\"98684\" src=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/968709_0.jpg\" alt=\"\" class=\"wp-image-98684\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/968709_0.jpg 1476w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/968709_0-300x225.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/968709_0-1024x769.jpg 1024w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/968709_0-768x577.jpg 768w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/968709_0-402x302.jpg 402w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/968709_0-819x615.jpg 819w\" sizes=\"(max-width: 1476px) 100vw, 1476px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1476\" height=\"1109\" data-id=\"98688\" src=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/968710_0.jpg\" alt=\"\" class=\"wp-image-98688\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/968710_0.jpg 1476w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/968710_0-300x225.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/968710_0-1024x769.jpg 1024w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/968710_0-768x577.jpg 768w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/968710_0-402x302.jpg 402w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/968710_0-819x615.jpg 819w\" sizes=\"(max-width: 1476px) 100vw, 1476px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1476\" height=\"1109\" data-id=\"98687\" src=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/968711_0.jpg\" alt=\"\" class=\"wp-image-98687\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/968711_0.jpg 1476w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/968711_0-300x225.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/968711_0-1024x769.jpg 1024w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/968711_0-768x577.jpg 768w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/968711_0-402x302.jpg 402w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/968711_0-819x615.jpg 819w\" sizes=\"(max-width: 1476px) 100vw, 1476px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1477\" height=\"1108\" data-id=\"98686\" src=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/968712_0.jpg\" alt=\"\" class=\"wp-image-98686\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/968712_0.jpg 1477w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/968712_0-300x225.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/968712_0-1024x768.jpg 1024w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/968712_0-768x576.jpg 768w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/968712_0-402x302.jpg 402w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/968712_0-819x614.jpg 819w\" sizes=\"(max-width: 1477px) 100vw, 1477px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"421\" src=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/11\/004kittinakorn.jpg\" alt=\"\" class=\"wp-image-62360\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/11\/004kittinakorn.jpg 1000w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/11\/004kittinakorn-300x126.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/11\/004kittinakorn-768x323.jpg 768w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/11\/004kittinakorn-402x169.jpg 402w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/11\/004kittinakorn-819x345.jpg 819w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u0e43\u0e19\u0e17\u0e38\u0e01\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e21\u0e47\u0e14\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e42\u0e14\u0e22\u0e15\u0e19\u0e21\u0e2d [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":98685,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-98683","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-31"],"_links":{"self":[{"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/posts\/98683"}],"collection":[{"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/comments?post=98683"}],"version-history":[{"count":1,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/posts\/98683\/revisions"}],"predecessor-version":[{"id":98689,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/posts\/98683\/revisions\/98689"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/media\/98685"}],"wp:attachment":[{"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/media?parent=98683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/categories?post=98683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/tags?post=98683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}