{"id":99041,"date":"2026-05-21T21:39:51","date_gmt":"2026-05-21T14:39:51","guid":{"rendered":"https:\/\/prakannews.com\/home\/?p=99041"},"modified":"2026-05-21T21:39:54","modified_gmt":"2026-05-21T14:39:54","slug":"%e0%b8%95%e0%b8%b3%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b8%a0%e0%b8%b2%e0%b8%84-1-%e0%b9%82%e0%b8%8a%e0%b8%a7%e0%b9%8c%e0%b8%9f%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%a1%e0%b8%a3%e0%b8%a7%e0%b8%9a-%e0%b9%80","status":"publish","type":"post","link":"https:\/\/prakannews.com\/home\/2026\/05\/21\/%e0%b8%95%e0%b8%b3%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b8%a0%e0%b8%b2%e0%b8%84-1-%e0%b9%82%e0%b8%8a%e0%b8%a7%e0%b9%8c%e0%b8%9f%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%a1%e0%b8%a3%e0%b8%a7%e0%b8%9a-%e0%b9%80\/","title":{"rendered":"\u0e15\u0e33\u0e23\u0e27\u0e08\u0e20\u0e32\u0e04 1 \u0e42\u0e0a\u0e27\u0e4c\u0e1f\u0e2d\u0e23\u0e4c\u0e21&#8221;\u0e23\u0e27\u0e1a \u0e40\u0e1b\u0e32 K2 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e1e\u0e27\u0e01\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e02\u0e2d\u0e07\u0e01\u0e25\u0e32\u0e07\u0e22\u0e32\u0e40\u0e2a\u0e1e\u0e15\u0e34\u0e14\u0e08\u0e33\u0e19\u0e27\u0e19 45 \u0e01\u0e23\u0e30\u0e2a\u0e2d\u0e1a (\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 8,900,000 \u0e40\u0e21\u0e47\u0e14) \u0e0b\u0e38\u0e01\u0e0b\u0e48\u0e2d\u0e19\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e44\u0e21\u0e48\u0e21\u0e35\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e48\u0e07\u0e15\u0e48\u0e2d\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e0a\u0e31\u0e49\u0e19\u0e43\u0e19"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e15\u0e33\u0e23\u0e27\u0e08\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 \u0e42\u0e14\u0e22 \u0e1e\u0e25.\u0e15.\u0e2d.\u0e01\u0e34\u0e15\u0e15\u0e34\u0e4c\u0e23\u0e31\u0e10 \u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e40\u0e1e\u0e47\u0e0a\u0e23 \u0e1c\u0e1a.\u0e15\u0e23. , \u0e1e\u0e25.\u0e15.\u0e2d.\u0e2a\u0e33\u0e23\u0e32\u0e0d \u0e19\u0e27\u0e25\u0e21\u0e32 \u0e23\u0e2d\u0e07 \u0e1c\u0e1a.\u0e15\u0e23.,\/&nbsp; \u0e1c\u0e2d.\u0e28\u0e2d.\u0e1b\u0e2a.\u0e15\u0e23.,\u0e1e\u0e25.\u0e15.\u0e2d.\u0e2a\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u0e40\u0e22\u0e47\u0e19\u0e17\u0e49\u0e27\u0e21 \u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e34\u0e40\u0e28\u0e29 \u0e15\u0e23. \u0e41\u0e25\u0e30 \u0e1e\u0e25.\u0e15.\u0e17.\u0e01\u0e24\u0e29\u0e0e\u0e32 \u0e01\u0e32\u0e0d\u0e08\u0e19\u0e2d\u0e25\u0e07\u0e01\u0e23\u0e13\u0e4c \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22 \u0e1c\u0e1a.\u0e15\u0e23.&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e15\u0e33\u0e23\u0e27\u0e08\u0e20\u0e39\u0e18\u0e23\u0e20\u0e32\u0e04 \u0e51 \u0e42\u0e14\u0e22 \u0e1e\u0e25.\u0e15.\u0e17.\u0e27\u0e31\u0e12\u0e19\u0e32 \u0e22\u0e35\u0e48\u0e08\u0e35\u0e19 \u0e1c\u0e1a\u0e0a.\u0e20.\u0e51, \u0e1e\u0e25.\u0e15.\u0e15.\u0e1e\u0e23\u0e1e\u0e34\u0e17\u0e31\u0e01\u0e29\u0e4c \u0e23\u0e39\u0e49\u0e22\u0e37\u0e19\u0e22\u0e07 \u0e23\u0e2d\u0e07 \u0e1c\u0e1a\u0e0a.\u0e20.1, \u0e1e\u0e25.\u0e15.\u0e15.\u0e2a\u0e16\u0e32\u0e1e\u0e23 \u0e40\u0e2d\u0e21\u0e42\u0e2d\u0e29\u0e10\u0e4c \u0e23\u0e2d\u0e07 \u0e08\u0e15\u0e23.\u0e0a\u0e48\u0e27\u0e22\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e23\u0e2d\u0e07 \u0e1c\u0e1a\u0e0a.\u0e20.1, \u0e1e\u0e25.\u0e15.\u0e15.\u0e27\u0e34\u0e0a\u0e34\u0e15 \u0e1a\u0e38\u0e0d\u0e0a\u0e34\u0e19\u0e27\u0e38\u0e12\u0e34\u0e01\u0e38\u0e25 \u0e23\u0e2d\u0e07 \u0e1c\u0e1a\u0e0a.\u0e20.\u0e51, \u0e1e\u0e25.\u0e15.\u0e15.\u0e2d\u0e20\u0e34\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e40\u0e27\u0e0a\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32 \u0e23\u0e2d\u0e07 \u0e1c\u0e1a\u0e0a.\u0e20.1, \u0e1e\u0e25.\u0e15.\u0e15.\u0e18\u0e23\u0e23\u0e21\u0e19\u0e39\u0e0d \u0e40\u0e0a\u0e32\u0e27\u0e30\u0e27\u0e19\u0e34\u0e0a\u0e22\u0e4c \u0e1c\u0e1a\u0e01.\u0e20.\u0e08\u0e27.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35, \u0e1e\u0e25.\u0e15.\u0e15.\u0e27\u0e23\u0e0a\u0e32\u0e15\u0e34 \u0e41\u0e2a\u0e19\u0e04\u0e33 \u0e1c\u0e1a\u0e01.\u0e2a\u0e2a.\u0e20.1, \u0e1e.\u0e15.\u0e2d.\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19 \u0e19\u0e31\u0e19\u0e17\u0e01\u0e2d\u0e1a\u0e01\u0e38\u0e25 \u0e23\u0e2d\u0e07 \u0e1c\u0e1a\u0e01.\u0e2a\u0e2a.\u0e20.1, \u0e1e.\u0e15.\u0e2d.\u0e27\u0e34\u0e28\u0e34\u0e29\u0e0f\u0e4c \u0e21\u0e30\u0e2d\u0e31\u0e01\u0e29\u0e23 \u0e23\u0e2d\u0e07 \u0e1c\u0e1a\u0e01.\u0e2a\u0e2a.\u0e20.1 \u0e20.\u0e08\u0e27.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1705\" height=\"960\" data-id=\"99045\" src=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/122463.jpg\" alt=\"\" class=\"wp-image-99045\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/122463.jpg 1705w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/122463-300x169.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/122463-1024x577.jpg 1024w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/122463-768x432.jpg 768w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/122463-1536x865.jpg 1536w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/122463-402x226.jpg 402w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/122463-819x461.jpg 819w\" sizes=\"auto, (max-width: 1705px) 100vw, 1705px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1705\" height=\"960\" data-id=\"99042\" src=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/123242_0.jpg\" alt=\"\" class=\"wp-image-99042\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/123242_0.jpg 1705w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/123242_0-300x169.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/123242_0-1024x577.jpg 1024w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/123242_0-768x432.jpg 768w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/123242_0-1536x865.jpg 1536w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/123242_0-402x226.jpg 402w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/123242_0-819x461.jpg 819w\" sizes=\"auto, (max-width: 1705px) 100vw, 1705px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1705\" height=\"960\" data-id=\"99044\" src=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/123243_0.jpg\" alt=\"\" class=\"wp-image-99044\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/123243_0.jpg 1705w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/123243_0-300x169.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/123243_0-1024x577.jpg 1024w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/123243_0-768x432.jpg 768w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/123243_0-1536x865.jpg 1536w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/123243_0-402x226.jpg 402w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/123243_0-819x461.jpg 819w\" sizes=\"auto, (max-width: 1705px) 100vw, 1705px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1705\" height=\"960\" data-id=\"99043\" src=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/123244_0.jpg\" alt=\"\" class=\"wp-image-99043\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/123244_0.jpg 1705w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/123244_0-300x169.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/123244_0-1024x577.jpg 1024w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/123244_0-768x432.jpg 768w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/123244_0-1536x865.jpg 1536w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/123244_0-402x226.jpg 402w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/123244_0-819x461.jpg 819w\" sizes=\"auto, (max-width: 1705px) 100vw, 1705px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1706\" height=\"960\" data-id=\"99046\" src=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/S__909323.jpg\" alt=\"\" class=\"wp-image-99046\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/S__909323.jpg 1706w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/S__909323-300x169.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/S__909323-1024x576.jpg 1024w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/S__909323-768x432.jpg 768w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/S__909323-1536x864.jpg 1536w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/S__909323-402x226.jpg 402w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/S__909323-819x461.jpg 819w\" sizes=\"auto, (max-width: 1706px) 100vw, 1706px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e42\u0e14\u0e22 \u0e1e\u0e25.\u0e15.\u0e15.\u0e18\u0e23\u0e23\u0e21\u0e19\u0e39\u0e0d \u0e40\u0e0a\u0e32\u0e27\u0e30\u0e27\u0e19\u0e34\u0e0a\u0e22\u0e4c \u0e1c\u0e1a\u0e01.\u0e20.\u0e08\u0e27.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35, \u0e1e.\u0e15.\u0e2d.\u0e40\u0e01\u0e29\u0e14\u0e32 \u0e27\u0e31\u0e0a\u0e23\u0e32\u0e19\u0e19\u0e17\u0e4c \u0e23\u0e2d\u0e07 \u0e1c\u0e1a\u0e01.\u0e20.\u0e08\u0e27.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35, \u0e1e.\u0e15.\u0e2d.\u0e2a\u0e38\u0e23\u0e34\u0e22\u0e30 \u0e2a\u0e38\u0e14\u0e01\u0e31\u0e07\u0e27\u0e32\u0e25 \u0e23\u0e2d\u0e07 \u0e1c\u0e1a\u0e01.\u0e20.\u0e08\u0e27.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u0e1e.\u0e15.\u0e2d.\u0e44\u0e01\u0e23\u0e2a\u0e23 \u0e28\u0e23\u0e35\u0e2d\u0e33\u0e1e\u0e23 \u0e1c\u0e01\u0e01.\u0e2a\u0e2a.\u0e20.\u0e08\u0e27.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\/\u0e2b\u0e31\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e0a\u0e1b\u0e2a.\u0e28\u0e2d.\u0e1b\u0e2a.\u0e20.\u0e51 \u0e0a\u0e38\u0e14\u0e17\u0e35\u0e48 \u0e52 \u0e20.\u0e08\u0e27.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e42\u0e14\u0e22 \u0e1e\u0e25.\u0e15.\u0e15.\u0e1e\u0e35\u0e23\u0e1e\u0e25 \u0e42\u0e0a\u0e15\u0e34\u0e01\u0e40\u0e2a\u0e16\u0e35\u0e22\u0e23 \u0e1c\u0e1a\u0e01.\u0e20.\u0e08\u0e27.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35, \u0e1e.\u0e15.\u0e2d.\u0e18\u0e07\u0e23\u0e1a \u0e41\u0e08\u0e49\u0e07\u0e08\u0e34\u0e15 \u0e23\u0e2d\u0e07 \u0e1c\u0e1a\u0e01.\u0e20.\u0e08\u0e27.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35, \u0e1e.\u0e15.\u0e2d.\u0e01\u0e32\u0e19\u0e15\u0e20\u0e13 \u0e27\u0e23\u0e23\u0e13\u0e32 \u0e1c\u0e01\u0e01.\u0e2a\u0e20.\u0e04\u0e39\u0e04\u0e15, \u0e1e.\u0e15.\u0e2d.\u0e2d\u0e14\u0e34\u0e40\u0e23\u0e01 \u0e42\u0e1b\u0e18\u0e34\u0e1b\u0e31\u0e19 \u0e1c\u0e01\u0e01.\u0e2a\u0e20.\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e19\u0e49\u0e33\u0e08\u0e38\u0e2c\u0e32\u0e25\u0e07\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e01\u0e17.\u0e42\u0e14\u0e22 \u0e1e\u0e25.\u0e15.\u0e2d\u0e20\u0e34\u0e0a\u0e31\u0e22 \u0e17\u0e2d\u0e07\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e1c\u0e1a.\u0e02\u0e01\u0e17. \u0e02\u0e01\u0e17.\u0e28\u0e1b\u0e01.\u0e19\u0e2a\u0e28. \u0e42\u0e14\u0e22 \u0e1e.\u0e2d.\u0e28\u0e23\u0e32\u0e22\u0e38\u0e17\u0e18 \u0e1e\u0e31\u0e12\u0e19\u0e0a\u0e31\u0e22 \u0e1c\u0e1a.\u0e02\u0e01\u0e17.\u0e28\u0e1b\u0e01.\u0e19\u0e2a\u0e28. \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e1b.\u0e1b.\u0e2a. \u0e20\u0e32\u0e04 \u0e51 \u0e42\u0e14\u0e22 \u0e19\u0e32\u0e22\u0e2d\u0e33\u0e19\u0e32\u0e08 \u0e40\u0e2b\u0e25\u0e48\u0e32\u0e01\u0e2d\u0e17\u0e35 \u0e23\u0e2d\u0e07 \u0e40\u0e25\u0e02\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23 \u0e1b\u0e1b\u0e2a. \u0e23\u0e31\u0e01\u0e29\u0e32\u0e17\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e41\u0e17\u0e19 \u0e1c\u0e2d.\u0e1b\u0e1b\u0e2a.\u0e20.1, \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e28\u0e28\u0e34\u0e23\u0e31\u0e28\u0e21\u0e34\u0e4c \u0e19\u0e32\u0e21\u0e27\u0e07\u0e29\u0e4c \u0e1c\u0e2d.\u0e1a\u0e01.\u0e1b\u0e1b\u0e2a.\u0e20.\u0e51 \u0e41\u0e25\u0e30\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e43\u0e19\u0e2a\u0e31\u0e07\u0e01\u0e31\u0e14 \u0e44\u0e14\u0e49\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e2a\u0e37\u0e1a\u0e2a\u0e27\u0e19\u0e08\u0e31\u0e1a\u0e01\u0e38\u0e21 \u0e1c\u0e39\u0e49\u0e15\u0e49\u0e2d\u0e07\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e47\u0e1a\u0e1e\u0e31\u0e01\u0e22\u0e32\u0e40\u0e2a\u0e1e\u0e15\u0e34\u0e14\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u201c\u0e40\u0e1b\u0e32 K2 (\u0e04\u0e25\u0e2d\u0e07\u0e2a\u0e2d\u0e07 \u0e25\u0e33\u0e25\u0e39\u0e01\u0e01\u0e32)\u201d<br>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<br>\u0e08\u0e31\u0e1a\u0e01\u0e38\u0e21\u0e1c\u0e39\u0e49\u0e15\u0e49\u0e2d\u0e07\u0e2b\u0e32 4 \u0e23\u0e32\u0e22 \u0e04\u0e37\u0e2d\u0e19\u0e32\u0e22\u0e27\u0e34\u0e42\u0e23\u0e08\u0e19\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e1b\u0e32 \u0e2d\u0e32\u0e22\u0e38 42 \u0e1b\u0e35 \u0e20\u0e39\u0e21\u0e34\u0e25\u0e33\u0e40\u0e19\u0e32 \u0e15.\u0e04\u0e25\u0e2d\u0e07\u0e2a\u0e32\u0e21 \u0e2d.\u0e04\u0e25\u0e2d\u0e07\u0e2b\u0e25\u0e27\u0e07 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e19\u0e32\u0e22\u0e27\u0e31\u0e0a\u0e23\u0e1e\u0e07\u0e29\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e42\u0e15\u0e49\u0e07 \u0e2d\u0e32\u0e22\u0e38 31 \u0e1b\u0e35 \u0e20\u0e39\u0e21\u0e34\u0e25\u0e33\u0e40\u0e19\u0e32 \u0e15.\u0e1e\u0e23\u0e21\u0e40\u0e17\u0e1e \u0e2d.\u0e17\u0e48\u0e32\u0e15\u0e39\u0e21 \u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c&nbsp;\u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e1b\u0e23\u0e34\u0e09\u0e31\u0e15\u0e23\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e35 \u0e2d\u0e32\u0e22\u0e38 21 \u0e1b\u0e35 \u0e20\u0e39\u0e21\u0e34\u0e25\u0e33\u0e40\u0e19\u0e32 \u0e41\u0e02\u0e27\u0e07\u0e1a\u0e32\u0e07\u0e19\u0e32\u0e40\u0e2b\u0e19\u0e37\u0e2d \u0e40\u0e02\u0e15\u0e1a\u0e32\u0e07\u0e19\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 mrs.panatda \u0e2b\u0e23\u0e37\u0e2d\u0e1b\u0e25\u0e32\u0e22 \u0e2d\u0e32\u0e22\u0e38 19 \u0e1b\u0e35 \u0e2a\u0e31\u0e0d\u0e0a\u0e32\u0e15\u0e34\u0e25\u0e32\u0e27 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e02\u0e2d\u0e07\u0e01\u0e25\u0e32\u0e07 \u0e04\u0e37\u0e2d<br>\u0e51.\u0e22\u0e32\u0e40\u0e2a\u0e1e\u0e15\u0e34\u0e14\u0e43\u0e2b\u0e49\u0e42\u0e17\u0e29\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 1 (\u0e22\u0e32\u0e1a\u0e49\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e21\u0e17\u0e41\u0e2d\u0e21\u0e40\u0e1f\u0e15\u0e32\u0e21\u0e35\u0e19) \u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 8,900,000 \u0e40\u0e21\u0e47\u0e14<br>\u0e52.\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e32\u0e40\u0e2a\u0e1e\u0e15\u0e34\u0e14\u0e08\u0e33\u0e19\u0e27\u0e19 5 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e23\u0e27\u0e08\u0e22\u0e36\u0e14\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c 2 \u0e04\u0e31\u0e19<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e1e\u0e24\u0e15\u0e34\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e43\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e1a\u0e01\u0e38\u0e21 \u0e15\u0e32\u0e21\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e32\u0e1a\u0e1b\u0e23\u0e32\u0e21\u0e22\u0e32\u0e40\u0e2a\u0e1e\u0e15\u0e34\u0e14\u0e02\u0e2d\u0e07 \u0e2f\u0e1e\u0e13\u0e2f\u0e19\u0e32\u0e22\u0e01\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e17\u0e38\u0e01\u0e02\u0e4c \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e2a\u0e38\u0e02 \u0e1e\u0e34\u0e17\u0e31\u0e01\u0e29\u0e4c\u0e2a\u0e31\u0e19\u0e15\u0e34\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c \u0e1e\u0e34\u0e06\u0e32\u0e15\u0e22\u0e32\u0e40\u0e2a\u0e1e\u0e15\u0e34\u0e14\u0e1e\u0e34\u0e0a\u0e34\u0e15\u0e2d\u0e31\u0e19\u0e18\u0e1e\u0e32\u0e25 \u0e41\u0e25\u0e30 \u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e32\u0e1a\u0e1b\u0e23\u0e32\u0e21\u0e22\u0e32\u0e40\u0e2a\u0e1e\u0e15\u0e34\u0e14\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e1a\u0e31\u0e0d\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e15\u0e33\u0e23\u0e27\u0e08\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 \u0e2a\u0e31\u0e48\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49 \u0e15\u0e33\u0e23\u0e27\u0e08\u0e20\u0e39\u0e18\u0e23\u0e20\u0e32\u0e04 1 \u0e1a\u0e39\u0e23\u0e13\u0e32\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a \u0e08\u0e19\u0e17.\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e02\u0e48\u0e32\u0e27\u0e01\u0e23\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e17\u0e2b\u0e32\u0e23 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e1a\u0e31\u0e0d\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21\u0e1e\u0e34\u0e40\u0e28\u0e29 (\u0e02\u0e01\u0e17.\u0e28\u0e1b\u0e01.\u0e19\u0e2a\u0e28.) \u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e15\u0e33\u0e23\u0e27\u0e08\u0e01\u0e2d\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e15\u0e33\u0e23\u0e27\u0e08\u0e1b\u0e23\u0e32\u0e1a\u0e1b\u0e23\u0e32\u0e21\u0e22\u0e32\u0e40\u0e2a\u0e1e\u0e15\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 \u0e1b\u0e1b\u0e2a.\u0e20\u0e32\u0e04 1 \u0e44\u0e14\u0e49\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e02\u0e22\u0e32\u0e22\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e08\u0e31\u0e1a\u0e01\u0e38\u0e21\u0e01\u0e25\u0e38\u0e48\u0e21\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e22\u0e32\u0e40\u0e2a\u0e1e\u0e15\u0e34\u0e14\u0e41\u0e25\u0e30\u0e17\u0e35\u0e21\u0e25\u0e33\u0e40\u0e25\u0e35\u0e22\u0e07\u0e22\u0e32\u0e41\u0e2a\u0e1e\u0e15\u0e34\u0e14\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e22\u0e21\u0e32 \u0e08\u0e19\u0e01\u0e23\u0e30\u0e17\u0e31\u0e48\u0e07\u0e17\u0e23\u0e32\u0e1a\u0e27\u0e48\u0e32\u0e21\u0e35\u0e01\u0e25\u0e38\u0e48\u0e21\u0e17\u0e35\u0e21\u0e1e\u0e31\u0e01\u0e22\u0e32\u0e40\u0e2a\u0e1e\u0e15\u0e34\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e33\u0e21\u0e32\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e01\u0e25\u0e38\u0e48\u0e21\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e15\u0e2d\u0e19\u0e43\u0e19\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e42\u0e14\u0e22\u0e01\u0e25\u0e38\u0e48\u0e21\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e31\u0e49\u0e07\u0e0a\u0e32\u0e22\u0e41\u0e25\u0e30\u0e2b\u0e0d\u0e34\u0e07 \u0e08\u0e33\u0e19\u0e27\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19 \u0e42\u0e14\u0e22\u0e08\u0e30\u0e19\u0e33\u0e22\u0e32\u0e40\u0e2a\u0e1e\u0e15\u0e34\u0e14\u0e21\u0e32\u0e40\u0e01\u0e47\u0e1a\u0e1e\u0e31\u0e01\u0e44\u0e27\u0e49\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 20 \u0e21.3 \u0e15.\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e18\u0e34\u0e1b\u0e31\u0e15\u0e22\u0e4c \u0e2d.\u0e18\u0e31\u0e0d\u0e1a\u0e38\u0e23\u0e35 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e44\u0e21\u0e48\u0e21\u0e35\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 \u0e0b\u0e2d\u0e22\u0e1a\u0e49\u0e32\u0e19\u0e1b\u0e31\u0e49\u0e19\u0e17\u0e2d\u0e07\u0e19\u0e34\u0e40\u0e27\u0e28\u0e19\u0e4c 3 \u0e15.\u0e04\u0e39\u0e04\u0e15 \u0e2d.\u0e25\u0e33\u0e25\u0e39\u0e01\u0e01\u0e32 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1706\" height=\"960\" data-id=\"99049\" src=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/S__49184788.jpg\" alt=\"\" class=\"wp-image-99049\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/S__49184788.jpg 1706w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/S__49184788-300x169.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/S__49184788-1024x576.jpg 1024w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/S__49184788-768x432.jpg 768w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/S__49184788-1536x864.jpg 1536w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/S__49184788-402x226.jpg 402w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/S__49184788-819x461.jpg 819w\" sizes=\"auto, (max-width: 1706px) 100vw, 1706px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1477\" height=\"1108\" data-id=\"99050\" src=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/S__64471067.jpg\" alt=\"\" class=\"wp-image-99050\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/S__64471067.jpg 1477w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/S__64471067-300x225.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/S__64471067-1024x768.jpg 1024w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/S__64471067-768x576.jpg 768w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/S__64471067-402x302.jpg 402w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/S__64471067-819x614.jpg 819w\" sizes=\"auto, (max-width: 1477px) 100vw, 1477px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1108\" height=\"1477\" data-id=\"99048\" src=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/S__98672647_0.jpg\" alt=\"\" class=\"wp-image-99048\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/S__98672647_0.jpg 1108w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/S__98672647_0-225x300.jpg 225w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/S__98672647_0-768x1024.jpg 768w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/S__98672647_0-402x536.jpg 402w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/S__98672647_0-300x400.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/S__98672647_0-819x1092.jpg 819w\" sizes=\"auto, (max-width: 1108px) 100vw, 1108px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1108\" height=\"1477\" data-id=\"99047\" src=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/S__98672648_0.jpg\" alt=\"\" class=\"wp-image-99047\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/S__98672648_0.jpg 1108w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/S__98672648_0-225x300.jpg 225w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/S__98672648_0-768x1024.jpg 768w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/S__98672648_0-402x536.jpg 402w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/S__98672648_0-300x400.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2026\/05\/S__98672648_0-819x1092.jpg 819w\" sizes=\"auto, (max-width: 1108px) 100vw, 1108px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e08\u0e19\u0e01\u0e23\u0e30\u0e17\u0e31\u0e48\u0e07\u0e0a\u0e48\u0e27\u0e07\u0e14\u0e36\u0e01\u0e02\u0e2d\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 19 \u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 20 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2569 \u0e1e\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e2b\u0e27\u0e02\u0e2d\u0e07\u0e01\u0e25\u0e38\u0e48\u0e21\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e41\u0e25\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e08\u0e31\u0e1a\u0e01\u0e38\u0e21 \u0e19\u0e32\u0e22\u0e27\u0e34\u0e42\u0e23\u0e08\u0e19\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e1b\u0e32, \u0e19\u0e32\u0e22\u0e27\u0e31\u0e0a\u0e23\u0e1e\u0e07\u0e29\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e42\u0e15\u0e49\u0e07, \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e1b\u0e23\u0e34\u0e09\u0e31\u0e15\u0e23\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e35 \u0e41\u0e25\u0e30 mrs.panatda \u0e2b\u0e23\u0e37\u0e2d\u0e1b\u0e25\u0e32\u0e22 \u0e44\u0e14\u0e49\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e02\u0e2d\u0e07\u0e01\u0e25\u0e32\u0e07\u0e22\u0e32\u0e40\u0e2a\u0e1e\u0e15\u0e34\u0e14\u0e08\u0e33\u0e19\u0e27\u0e19 45 \u0e01\u0e23\u0e30\u0e2a\u0e2d\u0e1a (\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 8,900,000 \u0e40\u0e21\u0e47\u0e14) \u0e0b\u0e36\u0e48\u0e07\u0e0b\u0e38\u0e01\u0e0b\u0e48\u0e2d\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e44\u0e21\u0e48\u0e21\u0e35\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 \u0e0b\u0e2d\u0e22\u0e1a\u0e49\u0e32\u0e19\u0e1b\u0e31\u0e49\u0e19\u0e17\u0e2d\u0e07\u0e19\u0e34\u0e40\u0e27\u0e28\u0e19\u0e4c 3 \u0e15.\u0e04\u0e39\u0e04\u0e15 \u0e2d.\u0e25\u0e33\u0e25\u0e39\u0e01\u0e01\u0e32 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e08\u0e33\u0e19\u0e27\u0e19 40 \u0e01\u0e23\u0e30\u0e2a\u0e2d\u0e1a(\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 8,000,000 \u0e40\u0e21\u0e47\u0e14) \u0e41\u0e25\u0e30\u0e0b\u0e38\u0e01\u0e0b\u0e48\u0e2d\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 20 \u0e21.3 \u0e15.\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e18\u0e34\u0e1b\u0e31\u0e15\u0e22\u0e4c \u0e2d.\u0e18\u0e31\u0e0d\u0e1a\u0e38\u0e23\u0e35 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e08\u0e33\u0e19\u0e27\u0e19 5 \u0e01\u0e23\u0e30\u0e2a\u0e2d\u0e1a(\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 900,000 \u0e40\u0e21\u0e47\u0e14)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e40\u0e2b\u0e15\u0e38\u0e40\u0e01\u0e34\u0e14\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e44\u0e21\u0e48\u0e21\u0e35\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48\u0e0b\u0e2d\u0e22\u0e1a\u0e49\u0e32\u0e19\u0e1b\u0e31\u0e49\u0e19\u0e17\u0e2d\u0e07\u0e19\u0e34\u0e40\u0e27\u0e28\u0e19\u0e4c 3 \u0e15.\u0e04\u0e39\u0e04\u0e15 \u0e2d.\u0e25\u0e33\u0e25\u0e39\u0e01\u0e01\u0e32 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u0e1a\u0e49\u0e32\u0e19\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 20 \u0e21.3 \u0e15.\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e18\u0e34\u0e1b\u0e31\u0e15\u0e22\u0e4c \u0e2d.\u0e18\u0e31\u0e0d\u0e1a\u0e38\u0e23\u0e35 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 20 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2569 \u0e40\u0e27\u0e25\u0e32\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 03.30 \u0e19. \u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 20 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2569 \u0e40\u0e27\u0e25\u0e32\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 10.30 \u0e19.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e43\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e1a\u0e01\u0e38\u0e21\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e22\u0e31\u0e1a\u0e22\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e23\u0e48\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e22\u0e32\u0e40\u0e2a\u0e1e\u0e15\u0e34\u0e14\u0e44\u0e1b\u0e2a\u0e39\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e44\u0e14\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e08\u0e33\u0e19\u0e27\u0e19\u0e21\u0e32\u0e01 \u0e0b\u0e36\u0e48\u0e07\u0e22\u0e32\u0e40\u0e2a\u0e1e\u0e15\u0e34\u0e14\u0e02\u0e2d\u0e07\u0e01\u0e25\u0e32\u0e07\u0e2b\u0e32\u0e01\u0e16\u0e39\u0e01\u0e19\u0e33\u0e2d\u0e2d\u0e01\u0e02\u0e32\u0e22\u0e2a\u0e39\u0e48\u0e17\u0e49\u0e2d\u0e07\u0e15\u0e25\u0e32\u0e14\u0e08\u0e30\u0e21\u0e35\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e01\u0e27\u0e48\u0e32 300,000,000 \u0e1a\u0e32\u0e17&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e0a\u0e38\u0e14\u0e08\u0e31\u0e1a\u0e01\u0e38\u0e21\u0e08\u0e30\u0e44\u0e14\u0e49\u0e02\u0e22\u0e32\u0e22\u0e1c\u0e25\u0e16\u0e36\u0e07\u0e01\u0e25\u0e38\u0e48\u0e21\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 \u0e1c\u0e39\u0e49\u0e2a\u0e31\u0e48\u0e07\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e22\u0e32\u0e40\u0e2a\u0e1e\u0e15\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e1c\u0e34\u0e14 \u0e42\u0e14\u0e22\u0e08\u0e30\u0e19\u0e33\u0e21\u0e32\u0e15\u0e23\u0e01\u0e32\u0e23\u0e2a\u0e21\u0e04\u0e1a\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d \u0e1f\u0e2d\u0e01\u0e40\u0e07\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e22\u0e36\u0e14\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e01\u0e31\u0e1a\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e22\u0e32\u0e40\u0e2a\u0e1e\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e44\u0e1b<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"190\" src=\"http:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/09\/008-songwitaya-2.jpg\" alt=\"\" class=\"wp-image-59998\" srcset=\"https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/09\/008-songwitaya-2.jpg 1000w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/09\/008-songwitaya-2-300x57.jpg 300w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/09\/008-songwitaya-2-768x146.jpg 768w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/09\/008-songwitaya-2-402x76.jpg 402w, https:\/\/prakannews.com\/home\/wp-content\/uploads\/2023\/09\/008-songwitaya-2-819x156.jpg 819w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e42\u0e14\u0e22\u0e15\u0e33\u0e23\u0e27\u0e08\u0e20\u0e39\u0e18\u0e23\u0e20\u0e32\u0e04 1 \u0e1e\u0e25.\u0e15.\u0e15.\u0e2d\u0e23\u0e23\u0e16\u0e1e\u0e25 \u0e2d\u0e19\u0e38\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e23\u0e2d\u0e07 \u0e1c\u0e1a\u0e0a.\u0e20.1\/\u0e42\u0e06\u0e29\u0e01 \u0e15\u0e23.\u0e20.1 \u0e1e\u0e25.\u0e15.\u0e15.\u0e20\u0e31\u0e04\u0e1e\u0e07\u0e28\u0e4c \u0e2a\u0e32\u0e22\u0e2d\u0e38\u0e1a\u0e25 \u0e1c\u0e1a\u0e01.\u0e2d\u0e01.\u0e20.1\/\u0e23\u0e2d\u0e07\u0e42\u0e06\u0e29\u0e01 \u0e15\u0e23.\u0e20.1 \u0e1e\u0e25.\u0e15.\u0e15.\u0e24\u0e17\u0e18\u0e34\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e1b\u0e38\u0e4b\u0e22\u0e1e\u0e31\u0e19\u0e18\u0e27\u0e07\u0e28\u0e4c \u0e1c\u0e1a\u0e01.\u0e01\u0e04.\u0e20.1\/\u0e23\u0e2d\u0e07\u0e42\u0e06\u0e29\u0e01 \u0e15\u0e23.\u0e20.1 v\u0e40\u0e1b\u0e34\u0e14\u0e40\u0e1c\u0e22\u0e27\u0e48\u0e32 \u0e1e\u0e25.\u0e15.\u0e17.\u0e27\u0e31\u0e12\u0e19\u0e32 \u0e22\u0e35\u0e48\u0e08\u0e35\u0e19 \u0e1c\u0e1a\u0e0a.\u0e20.1 \u0e44\u0e14\u0e49\u0e21\u0e35\u0e01\u0e32\u0e23 \u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e1a\u0e31\u0e0d\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e15\u0e33\u0e23\u0e27\u0e08\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 \u0e14\u0e31\u0e07\u0e19\u0e35\u0e49<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e2b\u0e32\u0e01\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e2b\u0e32\u0e01\u0e1e\u0e1a\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e23\u0e16\u0e15\u0e49\u0e2d\u0e07\u0e2a\u0e07\u0e2a\u0e31\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e21\u0e35\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e33\u0e1c\u0e34\u0e14\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e22\u0e32\u0e40\u0e2a\u0e1e\u0e15\u0e34\u0e14\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e15\u0e33\u0e23\u0e27\u0e08\u0e17\u0e35\u0e48\u0e17\u0e48\u0e32\u0e19\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e2b\u0e23\u0e37\u0e2d \u0e2a\u0e32\u0e22\u0e14\u0e48\u0e27\u0e19 191 \u0e41\u0e25\u0e30 1599 \u0e15\u0e25\u0e2d\u0e14 24 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e15\u0e33\u0e23\u0e27\u0e08\u0e08\u0e30\u0e19\u0e33\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e44\u0e1b\u0e2a\u0e37\u0e1a\u0e2a\u0e27\u0e19\u0e02\u0e22\u0e32\u0e22\u0e1c\u0e25\u0e08\u0e31\u0e1a\u0e01\u0e38\u0e21\u0e1c\u0e39\u0e49\u0e01\u0e23\u0e30\u0e17\u0e33\u0e1c\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e44\u0e1b<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e15\u0e33\u0e23\u0e27\u0e08\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 \u0e42\u0e14\u0e22 \u0e1e\u0e25.\u0e15.\u0e2d.\u0e01\u0e34\u0e15\u0e15\u0e34\u0e4c\u0e23\u0e31\u0e10 \u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e40\u0e1e\u0e47\u0e0a\u0e23  [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":99049,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-99041","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-6"],"_links":{"self":[{"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/posts\/99041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/comments?post=99041"}],"version-history":[{"count":1,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/posts\/99041\/revisions"}],"predecessor-version":[{"id":99051,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/posts\/99041\/revisions\/99051"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/media\/99049"}],"wp:attachment":[{"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/media?parent=99041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/categories?post=99041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prakannews.com\/home\/wp-json\/wp\/v2\/tags?post=99041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}